{"id":256273,"date":"2022-04-18T10:30:19","date_gmt":"2022-04-18T10:30:19","guid":{"rendered":"https:\/\/soeasytravelinsurance.com\/?page_id=256273"},"modified":"2025-12-17T10:34:44","modified_gmt":"2025-12-17T10:34:44","slug":"bulgaria-travel-insurance","status":"publish","type":"page","link":"https:\/\/soeasytravelinsurance.com\/fr\/bulgaria-travel-insurance\/","title":{"rendered":"Assurance voyage Bulgarie"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb admin_label=\u00a0\u00bbHero\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; use_background_color_gradient=\u00a0\u00bbon\u00a0\u00bb background_color_gradient_type=\u00a0\u00bbcircular\u00a0\u00bb background_color_gradient_direction_radial=\u00a0\u00bbtop right\u00a0\u00bb background_color_gradient_stops=\u00a0\u00bbrgba(0,0,0,0.32) 10%|rgba(0,0,0,0.32) 100%\u00a0\u00bb background_color_gradient_overlays_image=\u00a0\u00bbon\u00a0\u00bb background_color_gradient_start=\u00a0\u00bbrgba(0,0,0,0.32)\u00a0\u00bb background_color_gradient_start_position=\u00a0\u00bb10%\u00a0\u00bb background_color_gradient_end=\u00a0\u00bbrgba(0,0,0,0.32)\u00a0\u00bb background_image=\u00a0\u00bbhttps:\/\/soeasytravelinsurance.com\/wp-content\/uploads\/2022\/04\/view-air-plane-wing-during-take-off-landing-1-scaled-1.jpg\u00a0\u00bb background_position=\u00a0\u00bbtop_center\u00a0\u00bb background_vertical_offset=\u00a0\u00bb42%\u00a0\u00bb custom_padding=\u00a0\u00bb80px|0|150px||false|false\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb0|0|150px||false|false\u00a0\u00bb custom_padding_phone=\u00a0\u00bb0|0|40px||false|false\u00a0\u00bb background_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb background_vertical_offset_phone=\u00a0\u00bb70%\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row custom_padding_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color_gradient_direction=\u00a0\u00bb90deg\u00a0\u00bb background_color_gradient_start=\u00a0\u00bb#0C316B\u00a0\u00bb background_color_gradient_end=\u00a0\u00bb#081131&Prime; width_last_edited=\u00a0\u00bboff|desktop\u00a0\u00bb custom_padding=\u00a0\u00bb8px|0px|8px|0px|true|true\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb5px||5px||true|false\u00a0\u00bb custom_padding_phone=\u00a0\u00bb60px||||false|true\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_menu menu_id=\u00a0\u00bb11&Prime; active_link_color=\u00a0\u00bb#f58233&Prime; dropdown_menu_bg_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb dropdown_menu_line_color=\u00a0\u00bb#f58233&Prime; dropdown_menu_text_color=\u00a0\u00bb#000000&Prime; dropdown_menu_active_link_color=\u00a0\u00bb#f58233&Prime; mobile_menu_bg_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb mobile_menu_text_color=\u00a0\u00bb#000000&Prime; logo=\u00a0\u00bbhttps:\/\/soeasytravelinsurance.com\/wp-content\/uploads\/2022\/06\/logo-1-36.png\u00a0\u00bb logo_url=\u00a0\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoiaG9tZV91cmwiLCJzZXR0aW5ncyI6e319@\u00a0\u00bb logo_width=\u00a0\u00bb120%\u00a0\u00bb logo_max_width=\u00a0\u00bb260px\u00a0\u00bb logo_max_height=\u00a0\u00bb230px\u00a0\u00bb cart_icon_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb search_icon_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb menu_icon_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb mobile_menu_text_color_last_edited=\u00a0\u00bboff|desktop\u00a0\u00bb logo_max_width_tablet=\u00a0\u00bb260px\u00a0\u00bb logo_max_width_phone=\u00a0\u00bb350px\u00a0\u00bb logo_max_width_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.4&Prime; _dynamic_attributes=\u00a0\u00bblogo_url\u00a0\u00bb _module_preset=\u00a0\u00bbdefault\u00a0\u00bb menu_font=\u00a0\u00bbPoppins||||||||\u00a0\u00bb menu_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb menu_font_size=\u00a0\u00bb16px\u00a0\u00bb background_enable_color=\u00a0\u00bboff\u00a0\u00bb text_orientation=\u00a0\u00bbright\u00a0\u00bb width_last_edited=\u00a0\u00bboff|desktop\u00a0\u00bb custom_margin=\u00a0\u00bb||15px|||\u00a0\u00bb custom_padding=\u00a0\u00bb||0px||false|false\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb mobile_menu_text_color__hover_enabled=\u00a0\u00bboff|desktop\u00a0\u00bb][\/et_pb_menu][et_pb_code _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<script><!-- [et_pb_line_break_holder] -->(function($) { <!-- [et_pb_line_break_holder] -->    function setup_collapsible_submenus() {<!-- [et_pb_line_break_holder] -->        \/\/ mobile menu<!-- [et_pb_line_break_holder] -->        $('.mobile_nav .menu-item-has-children > a').after('<span class=\"menu-closed\"><\/span>');<!-- [et_pb_line_break_holder] -->        $('.mobile_nav .menu-item-has-children > a').each(function() {<!-- [et_pb_line_break_holder] -->            $(this).next().next('.sub-menu').toggleClass('hide',1000);<!-- [et_pb_line_break_holder] -->        });<!-- [et_pb_line_break_holder] -->        $('.mobile_nav .menu-item-has-children > a + span').on('click', function(event) {<!-- [et_pb_line_break_holder] -->            event.preventDefault();<!-- [et_pb_line_break_holder] -->            $(this).toggleClass('menu-open');<!-- [et_pb_line_break_holder] -->            $(this).next('.sub-menu').toggleClass('hide',1000);<!-- [et_pb_line_break_holder] -->        });<!-- [et_pb_line_break_holder] -->    }<!-- [et_pb_line_break_holder] -->    $(window).load(function() {<!-- [et_pb_line_break_holder] -->        setTimeout(function() {<!-- [et_pb_line_break_holder] -->            setup_collapsible_submenus();<!-- [et_pb_line_break_holder] -->        }, 700);<!-- [et_pb_line_break_holder] -->    });<!-- [et_pb_line_break_holder] -->})(jQuery);<!-- [et_pb_line_break_holder] --><\/script><!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] --><\/p>\n<style><!-- [et_pb_line_break_holder] -->\/*edit the Divi submenu*\/<!-- [et_pb_line_break_holder] -->.dp_header_v22.et_pb_menu .nav li ul {<!-- [et_pb_line_break_holder] -->margin-top:10px!important;<!-- [et_pb_line_break_holder] -->padding:0!important;<!-- [et_pb_line_break_holder] -->box-shadow: 0 5px 30px 5px rgb(69 79 91 \/ 20%);<!-- [et_pb_line_break_holder] -->border-top: none;<!-- [et_pb_line_break_holder] -->text-align:left;<!-- [et_pb_line_break_holder] -->border-radius:5px;<!-- [et_pb_line_break_holder] -->}<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->\/*add point on top of the Divi menu submenu dropdown*\/<!-- [et_pb_line_break_holder] -->.dp_header_v22 nav>ul>li>ul:after {<!-- [et_pb_line_break_holder] -->position: absolute;<!-- [et_pb_line_break_holder] -->left: 20%;<!-- [et_pb_line_break_holder] -->margin-left: -20px;<!-- [et_pb_line_break_holder] -->top: -14px;<!-- [et_pb_line_break_holder] -->width: 0;<!-- [et_pb_line_break_holder] -->height: 0;<!-- [et_pb_line_break_holder] -->content: '';<!-- [et_pb_line_break_holder] -->border-left: 15px solid transparent;<!-- [et_pb_line_break_holder] -->border-right: 15px solid transparent;<!-- [et_pb_line_break_holder] -->border-bottom: 15px solid #ffffff;<!-- [et_pb_line_break_holder] -->}<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->\/*edit the Divi submenu list items*\/<!-- [et_pb_line_break_holder] -->.dp_header_v22.et_pb_menu .nav li ul.sub-menu a {<!-- [et_pb_line_break_holder] -->padding:12px 0px !important; <!-- [et_pb_line_break_holder] -->}<!-- [et_pb_line_break_holder] -->  <!-- [et_pb_line_break_holder] -->\/*edit the Divi submenu list items*\/<!-- [et_pb_line_break_holder] -->.dp_header_v22.et_pb_menu .nav li ul.sub-menu a:hover {<!-- [et_pb_line_break_holder] -->background:transparent!important;<!-- [et_pb_line_break_holder] -->}<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->.dp_header_v22 .nav li li:not(:last-child) {<!-- [et_pb_line_break_holder] -->border-bottom: 1px solid rgb(0,0,0,0.1);<!-- [et_pb_line_break_holder] -->}<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->\/*change Divi hamburger menu to X*\/<!-- [et_pb_line_break_holder] -->.dp_header_v22 .mobile_nav.opened .mobile_menu_bar:before {<!-- [et_pb_line_break_holder] -->content: '\\4d';<!-- [et_pb_line_break_holder] -->}<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->\/*edit the Divi mobile menu*\/<!-- [et_pb_line_break_holder] -->.dp_header_v22 .et_mobile_menu{<!-- [et_pb_line_break_holder] -->margin-top:10px;<!-- [et_pb_line_break_holder] -->box-shadow: 0 5px 30px 5px rgb(69 79 91 \/ 20%);<!-- [et_pb_line_break_holder] -->border-radius:5px;<!-- [et_pb_line_break_holder] -->padding:0!important;<!-- [et_pb_line_break_holder] -->}<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->.dp_header_v22 .mobile_nav .menu-item-has-children > a {<!-- [et_pb_line_break_holder] -->background: transparent;<!-- [et_pb_line_break_holder] -->color: #000!important;<!-- [et_pb_line_break_holder] -->}<!-- [et_pb_line_break_holder] -->  <!-- [et_pb_line_break_holder] -->@media screen and (max-width: 980px){<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->.dp_header_v22 .et_pb_menu_inner_container {<!-- [et_pb_line_break_holder] -->    display: flex;<!-- [et_pb_line_break_holder] -->}<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->.dp_header_v22 .et_pb_menu__wrap {<!-- [et_pb_line_break_holder] -->    justify-content:flex-end!important;<!-- [et_pb_line_break_holder] -->}<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->}<!-- [et_pb_line_break_holder] -->  <!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->\/**** Divi Mobile Menu Collapse Effect ****\/<!-- [et_pb_line_break_holder] -->\/**** This hides the sub menu items on mobile ****\/<!-- [et_pb_line_break_holder] -->#page-container .mobile_nav li ul.hide {<!-- [et_pb_line_break_holder] -->display: none !important;<!-- [et_pb_line_break_holder] -->}<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->\/**** This adjusts the positioning and the background transparency of the parent menu item on mobile ****\/<!-- [et_pb_line_break_holder] -->#page-container .mobile_nav .menu-item-has-children {<!-- [et_pb_line_break_holder] -->position: relative;<!-- [et_pb_line_break_holder] -->}<!-- [et_pb_line_break_holder] -->#page-container .mobile_nav .menu-item-has-children > a {<!-- [et_pb_line_break_holder] -->background: transparent;<!-- [et_pb_line_break_holder] -->}<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->\/**** This styles the icon and moves it to the right ****\/<!-- [et_pb_line_break_holder] -->#page-container .mobile_nav .menu-item-has-children > a + span {<!-- [et_pb_line_break_holder] -->position: absolute;<!-- [et_pb_line_break_holder] -->right: 0;<!-- [et_pb_line_break_holder] -->top: 0;<!-- [et_pb_line_break_holder] -->padding: 10px 20px;<!-- [et_pb_line_break_holder] -->font-size: 20px;<!-- [et_pb_line_break_holder] -->font-weight: 700;<!-- [et_pb_line_break_holder] -->cursor: pointer;<!-- [et_pb_line_break_holder] -->z-index: 3;<!-- [et_pb_line_break_holder] -->}<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->\/**** Here you can swap out the actual icons ****\/<!-- [et_pb_line_break_holder] -->#page-container span.menu-closed:before {<!-- [et_pb_line_break_holder] -->content: \"\\4c\";<!-- [et_pb_line_break_holder] -->display: block;<!-- [et_pb_line_break_holder] -->color: #000;<!-- [et_pb_line_break_holder] -->font-size: 16px;<!-- [et_pb_line_break_holder] -->font-family: ETmodules;<!-- [et_pb_line_break_holder] -->}<!-- [et_pb_line_break_holder] -->#page-container span.menu-closed.menu-open:before {<!-- [et_pb_line_break_holder] -->content: \"\\4d\";<!-- [et_pb_line_break_holder] -->}<!-- [et_pb_line_break_holder] --><\/style>\n<p>[\/et_pb_code][\/et_pb_column][\/et_pb_row][et_pb_row custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; custom_margin=\u00a0\u00bb|||\u00a0\u00bb custom_padding=\u00a0\u00bb82px||||false|false\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb150px||||false|false\u00a0\u00bb custom_padding_phone=\u00a0\u00bb120px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.25.1&Prime; text_font=\u00a0\u00bbPoppins|300|||||||\u00a0\u00bb text_font_size=\u00a0\u00bb16px\u00a0\u00bb text_line_height=\u00a0\u00bb2em\u00a0\u00bb header_font=\u00a0\u00bbMontserrat|800|||||||\u00a0\u00bb header_font_size=\u00a0\u00bb54px\u00a0\u00bb header_line_height=\u00a0\u00bb1.4em\u00a0\u00bb background_layout=\u00a0\u00bbdark\u00a0\u00bb max_width=\u00a0\u00bb1019px\u00a0\u00bb custom_padding=\u00a0\u00bb|48px||||\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb\u00a0\u00bb text_font_size_phone=\u00a0\u00bb16px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_font_size_tablet=\u00a0\u00bb44px\u00a0\u00bb header_font_size_phone=\u00a0\u00bb24px\u00a0\u00bb header_font_size_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb header_line_height_tablet=\u00a0\u00bb1.4em\u00a0\u00bb header_line_height_phone=\u00a0\u00bb1.4em\u00a0\u00bb header_line_height_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h1>Assurance voyage Bulgarie<\/h1>\n<p>Lorsque vous voyagez \u00e0 l\u2019\u00e9tranger, il est essentiel d\u2019avoir la bonne assurance voyage pour garantir que votre voyage se d\u00e9roule en toute s\u00e9curit\u00e9 et sans stress. La Bulgarie propose une assurance voyage compl\u00e8te qui couvre divers risques et accidents pouvant survenir pendant votre voyage. Que vous envisagiez de voyager pour le plaisir ou pour les affaires, vous trouverez une gamme d&rsquo;options d&rsquo;assurance en ligne. Durant votre voyage, souscrire une assurance voyage vous procurera une tranquillit\u00e9 d\u2019esprit, sachant que vous \u00eates prot\u00e9g\u00e9 contre les impr\u00e9vus. La couverture d&rsquo;assurance en Bulgarie comprend l&rsquo;assistance m\u00e9dicale, la couverture contre les accidents, etc.<\/p>\n<p>Vous pouvez facilement rechercher et souscrire une assurance en ligne sur diverses plateformes, vous assurant ainsi de b\u00e9n\u00e9ficier de la meilleure couverture adapt\u00e9e \u00e0 vos besoins. Pour plus d\u2019informations sur l\u2019assurance voyage et les couvertures sp\u00e9cifiques offertes, vous pouvez visiter le site Web de la compagnie d\u2019assurance ou consulter le menu en ligne pour des informations d\u00e9taill\u00e9es. Que vous recherchiez plus d\u2019informations ou que vous soyez pr\u00eat \u00e0 souscrire votre assurance voyage, les ressources en ligne disponibles rendent la t\u00e2che pratique et simple.<\/p>\n<p>[\/et_pb_text][et_pb_button button_url=\u00a0\u00bbhttps:\/\/my.soeasytravelinsurance.com\/s\/UqGL\u00a0\u00bb url_new_window=\u00a0\u00bbon\u00a0\u00bb button_text=\u00a0\u00bbCOMMENCER UN DEVIS\u00a0\u00bb _builder_version=\u00a0\u00bb4.21.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_size=\u00a0\u00bb16px\u00a0\u00bb button_text_color=\u00a0\u00bb#ffffff\u00a0\u00bb button_bg_color=\u00a0\u00bb#f58233&Prime; button_border_width=\u00a0\u00bb0px\u00a0\u00bb button_border_radius=\u00a0\u00bb5px\u00a0\u00bb button_letter_spacing=\u00a0\u00bb2px\u00a0\u00bb button_font=\u00a0\u00bbRoboto|700||on|||||\u00a0\u00bb button_icon=\u00a0\u00bb&#x45;||divi||400&Prime; button_on_hover=\u00a0\u00bboff\u00a0\u00bb custom_padding=\u00a0\u00bb10px|42px|10px|25px|true|false\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb10px|15px|10px|15px|true|true\u00a0\u00bb custom_padding_phone=\u00a0\u00bb9px|31px|9px|13px|true|false\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb button_text_size_tablet=\u00a0\u00bb21px\u00a0\u00bb button_text_size_phone=\u00a0\u00bb15px\u00a0\u00bb button_text_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb button_bg_color_tablet=\u00a0\u00bb\u00a0\u00bb button_bg_color_phone=\u00a0\u00bb#f58233&Prime; button_bg_color_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb button_bg_enable_color_phone=\u00a0\u00bbon\u00a0\u00bb button_border_radius_tablet=\u00a0\u00bb0px\u00a0\u00bb button_border_radius_phone=\u00a0\u00bb5px\u00a0\u00bb button_border_radius_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb button_bg_color__hover=\u00a0\u00bbrgba(0,0,0,0)\u00a0\u00bb button_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_radius__hover=\u00a0\u00bb5px\u00a0\u00bb button_border_radius__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb button_letter_spacing__hover=\u00a0\u00bb3px\u00a0\u00bb button_letter_spacing__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb][\/et_pb_button][et_pb_image src=\u00a0\u00bbhttps:\/\/soeasytravelinsurance.com\/wp-content\/uploads\/2025\/10\/google.jpg\u00a0\u00bb title_text=\u00a0\u00bbgoogle\u00a0\u00bb url=\u00a0\u00bbhttps:\/\/www.google.com\/search?sca_esv=99f1a6d769628b16&#038;rlz=1C1GCEA_enCY999CY999&#038;sxsrf=AE3TifPnPloy8Gy98t7WTUEFs6CU1_2uCg:1758795298326&#038;si=AMgyJEtREmoPL4P1I5IDCfuA8gybfVI2d5Uj7QMwYCZHKDZ-E10Q063rmjDeX2XWDlW7RMUktuOkEGxDgz6ZPpq_ffNAbD199S2iwoqZZvO6HMfw5lCjfGqqpqDIdtgmx9erEMengjgOLQqyyUbxjsZllOfy7b3zKw%3D%3D&#038;q=SoEasy+Travel+Insurance+Reviews&#038;sa=X&#038;ved=2ahUKEwin7PSH1_OPAxWdTqQEHXI0KkEQ0bkNegQIIhAD\u00a0\u00bb url_new_window=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb||||false|false\u00a0\u00bb border_radii=\u00a0\u00bbon|10px|10px|10px|10px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb][\/et_pb_image][et_pb_code _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_orientation=\u00a0\u00bbleft\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb max_width=\u00a0\u00bb100%\u00a0\u00bb custom_margin=\u00a0\u00bb||||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb||||false|false\u00a0\u00bb link_option_url=\u00a0\u00bbhttps:\/\/www.trustpilot.com\/review\/soeasytravelinsurance.com\u00a0\u00bb link_option_url_new_window=\u00a0\u00bbon\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb]<div class=\"gutensuite-reviewkit_fpln_mcts gutensuite-reviewkit_fpln_common\"><div class=\"gutensuite-reviewkit_fpln_inner_left\"><span class=\"review_us_one\">Excellent<\/span><div class=\"gutensuite-reviewkit_score\"><span class=\"gutensuite-reviewkit_orignal_rcount\">4.8<\/span><span class=\"gutensuite-reviewkit_out_of\"> out of 5<\/span><\/div><\/div><div class=\"gutensuite-reviewkit_fpln_inner_right\"><img decoding=\"async\" src=\"https:\/\/soeasytravelinsurance.com\/wp-content\/plugins\/gutensuite-reviewkit\/assets\/images\/single-star.svg\" alt=\"Trustpilot logo\"  style=\"width: 20px;\" \/><span class=\"place_name\"> Trustpilot<\/span><\/div><\/div>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb admin_label=\u00a0\u00bbAbout\u00a0\u00bb _builder_version=\u00a0\u00bb4.25.1&Prime; custom_margin_tablet=\u00a0\u00bb\u00a0\u00bb custom_margin_phone=\u00a0\u00bb1px||||false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_padding=\u00a0\u00bb50px||0px||false|false\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb\u00a0\u00bb custom_padding_phone=\u00a0\u00bb9px||5px||false|false\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.16&Prime; custom_margin_tablet=\u00a0\u00bb\u00a0\u00bb custom_margin_phone=\u00a0\u00bb0px|auto||auto|false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_padding=\u00a0\u00bb12px||0px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.25.1&Prime; text_font=\u00a0\u00bb||||||||\u00a0\u00bb text_font_size=\u00a0\u00bb15px\u00a0\u00bb text_line_height=\u00a0\u00bb2em\u00a0\u00bb header_font=\u00a0\u00bb||||||||\u00a0\u00bb header_2_font=\u00a0\u00bbMontserrat|800|||||||\u00a0\u00bb header_2_font_size=\u00a0\u00bb27px\u00a0\u00bb header_2_line_height=\u00a0\u00bb1.5em\u00a0\u00bb header_3_font=\u00a0\u00bbRubik|500||on|||||\u00a0\u00bb header_3_text_color=\u00a0\u00bb#f58233&Prime; header_3_font_size=\u00a0\u00bb19px\u00a0\u00bb header_3_letter_spacing=\u00a0\u00bb2px\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb\u00a0\u00bb text_font_size_phone=\u00a0\u00bb14px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_2_font_size_tablet=\u00a0\u00bb32px\u00a0\u00bb header_2_font_size_phone=\u00a0\u00bb21px\u00a0\u00bb header_2_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_2_line_height_tablet=\u00a0\u00bb1.5em\u00a0\u00bb header_2_line_height_phone=\u00a0\u00bb0.8em\u00a0\u00bb header_2_line_height_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_3_font_size_tablet=\u00a0\u00bb19px\u00a0\u00bb header_3_font_size_phone=\u00a0\u00bb17px\u00a0\u00bb header_3_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3><span style=\"font-weight: 400;\">Qu&rsquo;est-ce que l&rsquo;assurance voyage ?<\/span><\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.16&Prime; custom_margin_tablet=\u00a0\u00bb\u00a0\u00bb custom_margin_phone=\u00a0\u00bb0px|auto||auto|false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_padding=\u00a0\u00bb12px||0px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.25.1&Prime; text_font=\u00a0\u00bbPoppins|300|||||||\u00a0\u00bb text_font_size=\u00a0\u00bb16px\u00a0\u00bb text_line_height=\u00a0\u00bb2em\u00a0\u00bb text_orientation=\u00a0\u00bbjustified\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb\u00a0\u00bb text_font_size_phone=\u00a0\u00bb16px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<span style=\"font-weight: 400;\">L&rsquo;assurance voyage est un filet de s\u00e9curit\u00e9 con\u00e7u pour vous prot\u00e9ger des impr\u00e9vus. Il couvre une gamme de probl\u00e8mes potentiels, depuis les urgences m\u00e9dicales et les annulations de voyage jusqu&rsquo;aux objets perdus et aux retards de voyage. Essentiellement, cela vous permet de profiter de votre voyage en toute tranquillit\u00e9 d&rsquo;esprit, sachant que vous \u00eates prot\u00e9g\u00e9 contre les perturbations impr\u00e9vues.<\/span>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb admin_label=\u00a0\u00bbAbout\u00a0\u00bb _builder_version=\u00a0\u00bb4.25.1&Prime; custom_margin_tablet=\u00a0\u00bb\u00a0\u00bb custom_margin_phone=\u00a0\u00bb1px||||false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_padding=\u00a0\u00bb50px||0px||false|false\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb\u00a0\u00bb custom_padding_phone=\u00a0\u00bb9px||5px||false|false\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.16&Prime; custom_margin_tablet=\u00a0\u00bb\u00a0\u00bb custom_margin_phone=\u00a0\u00bb0px|auto||auto|false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_padding=\u00a0\u00bb12px||0px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.25.1&Prime; text_font=\u00a0\u00bb||||||||\u00a0\u00bb text_font_size=\u00a0\u00bb15px\u00a0\u00bb text_line_height=\u00a0\u00bb2em\u00a0\u00bb header_font=\u00a0\u00bb||||||||\u00a0\u00bb header_2_font=\u00a0\u00bbMontserrat|800|||||||\u00a0\u00bb header_2_font_size=\u00a0\u00bb27px\u00a0\u00bb header_2_line_height=\u00a0\u00bb1.5em\u00a0\u00bb header_3_font=\u00a0\u00bbRubik|500||on|||||\u00a0\u00bb header_3_text_color=\u00a0\u00bb#f58233&Prime; header_3_font_size=\u00a0\u00bb19px\u00a0\u00bb header_3_letter_spacing=\u00a0\u00bb2px\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb\u00a0\u00bb text_font_size_phone=\u00a0\u00bb14px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_2_font_size_tablet=\u00a0\u00bb32px\u00a0\u00bb header_2_font_size_phone=\u00a0\u00bb21px\u00a0\u00bb header_2_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_2_line_height_tablet=\u00a0\u00bb1.5em\u00a0\u00bb header_2_line_height_phone=\u00a0\u00bb0.8em\u00a0\u00bb header_2_line_height_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_3_font_size_tablet=\u00a0\u00bb19px\u00a0\u00bb header_3_font_size_phone=\u00a0\u00bb17px\u00a0\u00bb header_3_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3><span style=\"font-weight: 400;\">Types de polices d&rsquo;assurance voyage<\/span><\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.16&Prime; custom_margin_tablet=\u00a0\u00bb\u00a0\u00bb custom_margin_phone=\u00a0\u00bb0px|auto||auto|false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_padding=\u00a0\u00bb12px||0px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.25.1&Prime; text_font=\u00a0\u00bbPoppins|300|||||||\u00a0\u00bb text_font_size=\u00a0\u00bb16px\u00a0\u00bb text_line_height=\u00a0\u00bb2em\u00a0\u00bb text_orientation=\u00a0\u00bbjustified\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb\u00a0\u00bb text_font_size_phone=\u00a0\u00bb16px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<span style=\"font-weight: 400;\">Il existe diff\u00e9rents types de polices d&rsquo;assurance voyage adapt\u00e9es \u00e0 diff\u00e9rents besoins :<\/span><\/p>\n<ul>\n<li><span style=\"font-weight: 400;\">Assurance voyage simple : vous couvre pour un voyage sp\u00e9cifique.<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Assurance multi-voyages : id\u00e9ale pour les voyageurs fr\u00e9quents, couvrant plusieurs voyages sur une p\u00e9riode d\u00e9finie.<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Assurance compl\u00e8te : comprend une couverture \u00e9tendue, des urgences m\u00e9dicales aux annulations de voyage.<\/span><\/li>\n<li>Assurance sp\u00e9cialis\u00e9e : adapt\u00e9e \u00e0 des activit\u00e9s sp\u00e9cifiques telles que les sports d&rsquo;aventure ou les voyages d&rsquo;affaires.<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb admin_label=\u00a0\u00bbAbout\u00a0\u00bb _builder_version=\u00a0\u00bb4.25.1&Prime; custom_margin_tablet=\u00a0\u00bb\u00a0\u00bb custom_margin_phone=\u00a0\u00bb1px||||false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_padding=\u00a0\u00bb50px||0px||false|false\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb\u00a0\u00bb custom_padding_phone=\u00a0\u00bb9px||5px||false|false\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; custom_margin=\u00a0\u00bb-50px||||false|false\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb\u00a0\u00bb custom_padding_phone=\u00a0\u00bb15px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.25.1&Prime; text_font=\u00a0\u00bb||||||||\u00a0\u00bb text_font_size=\u00a0\u00bb15px\u00a0\u00bb text_line_height=\u00a0\u00bb2em\u00a0\u00bb header_font=\u00a0\u00bb||||||||\u00a0\u00bb header_2_font=\u00a0\u00bbMontserrat|800|||||||\u00a0\u00bb header_2_font_size=\u00a0\u00bb27px\u00a0\u00bb header_2_line_height=\u00a0\u00bb1.5em\u00a0\u00bb header_3_font=\u00a0\u00bbRubik|500||on|||||\u00a0\u00bb header_3_text_color=\u00a0\u00bb#f58233&Prime; header_3_font_size=\u00a0\u00bb19px\u00a0\u00bb header_3_letter_spacing=\u00a0\u00bb2px\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb\u00a0\u00bb text_font_size_phone=\u00a0\u00bb14px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_2_font_size_tablet=\u00a0\u00bb32px\u00a0\u00bb header_2_font_size_phone=\u00a0\u00bb21px\u00a0\u00bb header_2_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_2_line_height_tablet=\u00a0\u00bb1.5em\u00a0\u00bb header_2_line_height_phone=\u00a0\u00bb0.8em\u00a0\u00bb header_2_line_height_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_3_font_size_tablet=\u00a0\u00bb19px\u00a0\u00bb header_3_font_size_phone=\u00a0\u00bb17px\u00a0\u00bb header_3_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3>Avantages de l&rsquo;assurance voyage<\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; custom_margin=\u00a0\u00bb-50px||||false|false\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb\u00a0\u00bb custom_padding_phone=\u00a0\u00bb15px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.25.1&Prime; text_font=\u00a0\u00bbPoppins|300|||||||\u00a0\u00bb text_font_size=\u00a0\u00bb16px\u00a0\u00bb text_line_height=\u00a0\u00bb2em\u00a0\u00bb text_orientation=\u00a0\u00bbjustified\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb\u00a0\u00bb text_font_size_phone=\u00a0\u00bb16px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<ul>\n<li><span style=\"font-weight: 400;\">Annulations de voyage : <\/span><span style=\"font-weight: 400;\">La vie est impr\u00e9visible. Si vous devez annuler votre voyage en raison de circonstances impr\u00e9vues comme une maladie ou une urgence familiale, l&rsquo;assurance voyage peut rembourser vos d\u00e9penses non remboursables.<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Objets perdus ou vol\u00e9s : <\/span><span style=\"font-weight: 400;\">Perdre vos bagages ou vous faire voler vos effets personnels peut g\u00e2cher un voyage . L&rsquo;assurance voyage indemnise les objets perdus ou vol\u00e9s, vous aidant \u00e0 remplacer rapidement les \u00e9l\u00e9ments essentiels.<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Retards de voyage : <\/span><span style=\"font-weight: 400;\">Les retards de vol sont fr\u00e9quents. L&rsquo;assurance peut fournir une compensation pour des d\u00e9penses suppl\u00e9mentaires telles que les repas et l&rsquo;h\u00e9bergement si vos projets de voyage sont perturb\u00e9s.<\/span><\/li>\n<\/ul>\n<p>[\/et_pb_text][et_pb_button button_url=\u00a0\u00bbhttps:\/\/my.soeasytravelinsurance.com\/travel-insurance\/details\u00a0\u00bb url_new_window=\u00a0\u00bbon\u00a0\u00bb button_text=\u00a0\u00bbAPPRENDRE ENCORE PLUS\u00a0\u00bb _builder_version=\u00a0\u00bb4.25.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_size=\u00a0\u00bb16px\u00a0\u00bb button_text_color=\u00a0\u00bb#ffffff\u00a0\u00bb button_bg_color=\u00a0\u00bb#f58233&Prime; button_border_width=\u00a0\u00bb0px\u00a0\u00bb button_border_radius=\u00a0\u00bb5px\u00a0\u00bb button_letter_spacing=\u00a0\u00bb2px\u00a0\u00bb button_font=\u00a0\u00bbRoboto|700||on|||||\u00a0\u00bb button_icon=\u00a0\u00bb&#x45;||divi||400&Prime; button_on_hover=\u00a0\u00bboff\u00a0\u00bb custom_padding=\u00a0\u00bb10px|42px|10px|25px|true|false\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb10px|15px|10px|15px|true|true\u00a0\u00bb custom_padding_phone=\u00a0\u00bb9px|31px|9px|13px|true|false\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb button_text_size_tablet=\u00a0\u00bb21px\u00a0\u00bb button_text_size_phone=\u00a0\u00bb15px\u00a0\u00bb button_text_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb button_bg_color_tablet=\u00a0\u00bb\u00a0\u00bb button_bg_color_phone=\u00a0\u00bb#f58233&Prime; button_bg_color_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb button_bg_enable_color_phone=\u00a0\u00bbon\u00a0\u00bb button_border_radius_tablet=\u00a0\u00bb0px\u00a0\u00bb button_border_radius_phone=\u00a0\u00bb5px\u00a0\u00bb button_border_radius_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb button_bg_color__hover=\u00a0\u00bbrgba(0,0,0,0)\u00a0\u00bb button_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_radius__hover=\u00a0\u00bb5px\u00a0\u00bb button_border_radius__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb button_letter_spacing__hover=\u00a0\u00bb3px\u00a0\u00bb button_letter_spacing__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb admin_label=\u00a0\u00bbAbout\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.4&Prime; custom_margin_tablet=\u00a0\u00bb\u00a0\u00bb custom_margin_phone=\u00a0\u00bb1px||||false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_padding=\u00a0\u00bb16px||0px|||\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb\u00a0\u00bb custom_padding_phone=\u00a0\u00bb9px||5px||false|false\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.16&Prime; custom_margin_tablet=\u00a0\u00bb\u00a0\u00bb custom_margin_phone=\u00a0\u00bb0px|auto||auto|false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_padding=\u00a0\u00bb12px||0px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.25.1&Prime; text_font=\u00a0\u00bb||||||||\u00a0\u00bb text_font_size=\u00a0\u00bb15px\u00a0\u00bb text_line_height=\u00a0\u00bb2em\u00a0\u00bb header_font=\u00a0\u00bb||||||||\u00a0\u00bb header_2_font=\u00a0\u00bbMontserrat|800|||||||\u00a0\u00bb header_2_font_size=\u00a0\u00bb27px\u00a0\u00bb header_2_line_height=\u00a0\u00bb1.5em\u00a0\u00bb header_3_font=\u00a0\u00bbRubik|500||on|||||\u00a0\u00bb header_3_text_color=\u00a0\u00bb#f58233&Prime; header_3_font_size=\u00a0\u00bb19px\u00a0\u00bb header_3_letter_spacing=\u00a0\u00bb2px\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb\u00a0\u00bb text_font_size_phone=\u00a0\u00bb14px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_2_font_size_tablet=\u00a0\u00bb32px\u00a0\u00bb header_2_font_size_phone=\u00a0\u00bb21px\u00a0\u00bb header_2_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_2_line_height_tablet=\u00a0\u00bb1.5em\u00a0\u00bb header_2_line_height_phone=\u00a0\u00bb0.8em\u00a0\u00bb header_2_line_height_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_3_font_size_tablet=\u00a0\u00bb19px\u00a0\u00bb header_3_font_size_phone=\u00a0\u00bb17px\u00a0\u00bb header_3_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3>Choisir la bonne assurance voyage Bulgarie<\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; custom_margin=\u00a0\u00bb-50px||||false|false\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb\u00a0\u00bb custom_padding_phone=\u00a0\u00bb15px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.25.1&Prime; text_font=\u00a0\u00bbPoppins|300|||||||\u00a0\u00bb text_font_size=\u00a0\u00bb16px\u00a0\u00bb text_line_height=\u00a0\u00bb2em\u00a0\u00bb text_orientation=\u00a0\u00bbjustified\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb\u00a0\u00bb text_font_size_phone=\u00a0\u00bb16px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><span style=\"font-weight: 400;\">\u00c9valuer vos besoins : <\/span><span style=\"font-weight: 400;\">R\u00e9fl\u00e9chissez aux raisons pour lesquelles vous avez besoin d&rsquo;une couverture : urgences m\u00e9dicales, annulations de voyage, objets perdus, ou des activit\u00e9s d&rsquo;aventure. Votre style de voyage et les activit\u00e9s pr\u00e9vues en Bulgarie guideront votre choix.<\/span><\/p>\n<ul>\n<li><span style=\"font-weight: 400;\">Comparaison de diff\u00e9rents fournisseurs : <\/span><span style=\"font-weight: 400;\">Toutes les polices d&rsquo; assurance voyage Bulgarie ne sont pas \u00e9gales. Comparez les diff\u00e9rents fournisseurs et leurs offres. Recherchez les avis et les notes des clients pour \u00e9valuer la fiabilit\u00e9 et la qualit\u00e9 du service.<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Lecture des petits caract\u00e8res : <\/span><span style=\"font-weight: 400;\">Comprenez ce qui est couvert et ce qui ne l&rsquo;est pas. Faites attention aux exclusions et aux limitations, en vous assurant que la police r\u00e9pond \u00e0 tous vos besoins.<\/span><\/li>\n<li>Couverture m\u00e9dicale en Bulgarie : <span>Syst\u00e8me de sant\u00e9 {<\/span><span>La Bulgarie poss\u00e8de un m\u00e9lange de syst\u00e8mes de sant\u00e9 publics et priv\u00e9s. M\u00eame si les soins de sant\u00e9 publics sont accessibles, ils ne r\u00e9pondent peut-\u00eatre pas aux normes auxquelles vous \u00eates habitu\u00e9. Les soins de sant\u00e9 priv\u00e9s sont meilleurs mais peuvent \u00eatre co\u00fbteux.<\/span><\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb admin_label=\u00a0\u00bbAbout\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.4&Prime; custom_margin_tablet=\u00a0\u00bb\u00a0\u00bb custom_margin_phone=\u00a0\u00bb1px||||false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_padding=\u00a0\u00bb16px||0px|||\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb\u00a0\u00bb custom_padding_phone=\u00a0\u00bb9px||5px||false|false\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.16&Prime; custom_margin_tablet=\u00a0\u00bb\u00a0\u00bb custom_margin_phone=\u00a0\u00bb0px|auto||auto|false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_padding=\u00a0\u00bb12px||0px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.25.1&Prime; text_font=\u00a0\u00bb||||||||\u00a0\u00bb text_font_size=\u00a0\u00bb15px\u00a0\u00bb text_line_height=\u00a0\u00bb2em\u00a0\u00bb header_font=\u00a0\u00bb||||||||\u00a0\u00bb header_2_font=\u00a0\u00bbMontserrat|800|||||||\u00a0\u00bb header_2_font_size=\u00a0\u00bb27px\u00a0\u00bb header_2_line_height=\u00a0\u00bb1.5em\u00a0\u00bb header_3_font=\u00a0\u00bbRubik|500||on|||||\u00a0\u00bb header_3_text_color=\u00a0\u00bb#f58233&Prime; header_3_font_size=\u00a0\u00bb19px\u00a0\u00bb header_3_letter_spacing=\u00a0\u00bb2px\u00a0\u00bb max_width=\u00a0\u00bb500px\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb\u00a0\u00bb text_font_size_phone=\u00a0\u00bb14px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_2_font_size_tablet=\u00a0\u00bb32px\u00a0\u00bb header_2_font_size_phone=\u00a0\u00bb21px\u00a0\u00bb header_2_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_2_line_height_tablet=\u00a0\u00bb1.5em\u00a0\u00bb header_2_line_height_phone=\u00a0\u00bb0.8em\u00a0\u00bb header_2_line_height_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_3_font_size_tablet=\u00a0\u00bb19px\u00a0\u00bb header_3_font_size_phone=\u00a0\u00bb17px\u00a0\u00bb header_3_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3>Assurance m\u00e9dicale en Bulgarie<\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; custom_margin=\u00a0\u00bb-50px||||false|false\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb\u00a0\u00bb custom_padding_phone=\u00a0\u00bb15px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.25.1&Prime; text_font=\u00a0\u00bbPoppins|300|||||||\u00a0\u00bb text_font_size=\u00a0\u00bb16px\u00a0\u00bb text_line_height=\u00a0\u00bb2em\u00a0\u00bb header_3_font=\u00a0\u00bbRubik|500||on|||||\u00a0\u00bb header_3_text_color=\u00a0\u00bb#f58233&Prime; header_3_font_size=\u00a0\u00bb19px\u00a0\u00bb header_3_letter_spacing=\u00a0\u00bb2px\u00a0\u00bb text_orientation=\u00a0\u00bbjustified\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb\u00a0\u00bb text_font_size_phone=\u00a0\u00bb16px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_3_font_size_tablet=\u00a0\u00bb19px\u00a0\u00bb header_3_font_size_phone=\u00a0\u00bb17px\u00a0\u00bb header_3_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<ul>\n<li><span style=\"font-weight: 400;\">Importance de la couverture m\u00e9dicale : <\/span><span style=\"font-weight: 400;\">Les urgences m\u00e9dicales peuvent \u00eatre co\u00fbteuses. Une assurance voyage Bulgarie couvrant les frais m\u00e9dicaux vous garantit de recevoir des soins de qualit\u00e9 sans vous soucier des co\u00fbts.<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Frais m\u00e9dicaux typiques : <\/span><span style=\"font-weight: 400;\">Un probl\u00e8me m\u00e9dical mineur peut entra\u00eener des d\u00e9penses importantes. Par exemple, une simple visite chez le m\u00e9decin peut co\u00fbter environ 50 \u20ac, tandis que les s\u00e9jours \u00e0 l&rsquo;h\u00f4pital peuvent se chiffrer en milliers.<\/span><\/li>\n<\/ul>\n<h3><span style=\"font-weight: 400;\">Couverture pour les annulations et interruptions de voyage<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Raisons courantes d&rsquo;annulation : <\/span><span style=\"font-weight: 400;\">La maladie, les urgences familiales et les engagements professionnels sont des raisons courantes pour lesquelles les voyageurs pourraient avoir besoin de annuler leurs voyages. L&rsquo; assurance voyage Bulgarie peut vous rembourser les d\u00e9penses non remboursables dans de tels cas.<\/span><\/p>\n<p>[\/et_pb_text][et_pb_button button_url=\u00a0\u00bbhttps:\/\/my.soeasytravelinsurance.com\/travel-insurance\/details\u00a0\u00bb url_new_window=\u00a0\u00bbon\u00a0\u00bb button_text=\u00a0\u00bbACHETER MAINTENANT\u00a0\u00bb _builder_version=\u00a0\u00bb4.25.1&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_size=\u00a0\u00bb16px\u00a0\u00bb button_text_color=\u00a0\u00bb#ffffff\u00a0\u00bb button_bg_color=\u00a0\u00bb#f58233&Prime; button_border_width=\u00a0\u00bb0px\u00a0\u00bb button_border_radius=\u00a0\u00bb5px\u00a0\u00bb button_letter_spacing=\u00a0\u00bb2px\u00a0\u00bb button_font=\u00a0\u00bbRoboto|700||on|||||\u00a0\u00bb button_icon=\u00a0\u00bb&#x45;||divi||400&Prime; button_on_hover=\u00a0\u00bboff\u00a0\u00bb custom_padding=\u00a0\u00bb10px|42px|10px|25px|true|false\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb10px|15px|10px|15px|true|true\u00a0\u00bb custom_padding_phone=\u00a0\u00bb9px|31px|9px|13px|true|false\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb button_text_size_tablet=\u00a0\u00bb21px\u00a0\u00bb button_text_size_phone=\u00a0\u00bb15px\u00a0\u00bb button_text_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb button_bg_color_tablet=\u00a0\u00bb\u00a0\u00bb button_bg_color_phone=\u00a0\u00bb#f58233&Prime; button_bg_color_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb button_bg_enable_color_phone=\u00a0\u00bbon\u00a0\u00bb button_border_radius_tablet=\u00a0\u00bb0px\u00a0\u00bb button_border_radius_phone=\u00a0\u00bb5px\u00a0\u00bb button_border_radius_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb button_bg_color__hover=\u00a0\u00bbrgba(0,0,0,0)\u00a0\u00bb button_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_radius__hover=\u00a0\u00bb5px\u00a0\u00bb button_border_radius__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb button_letter_spacing__hover=\u00a0\u00bb3px\u00a0\u00bb button_letter_spacing__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb admin_label=\u00a0\u00bbAbout\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.4&Prime; custom_margin_tablet=\u00a0\u00bb\u00a0\u00bb custom_margin_phone=\u00a0\u00bb1px||||false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_padding=\u00a0\u00bb16px||0px|||\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb\u00a0\u00bb custom_padding_phone=\u00a0\u00bb9px||5px||false|false\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.16&Prime; custom_margin_tablet=\u00a0\u00bb\u00a0\u00bb custom_margin_phone=\u00a0\u00bb0px|auto||auto|false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_padding=\u00a0\u00bb12px||0px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.25.1&Prime; text_font=\u00a0\u00bb||||||||\u00a0\u00bb text_font_size=\u00a0\u00bb15px\u00a0\u00bb text_line_height=\u00a0\u00bb2em\u00a0\u00bb header_font=\u00a0\u00bb||||||||\u00a0\u00bb header_2_font=\u00a0\u00bbMontserrat|800|||||||\u00a0\u00bb header_2_font_size=\u00a0\u00bb27px\u00a0\u00bb header_2_line_height=\u00a0\u00bb1.5em\u00a0\u00bb header_3_font=\u00a0\u00bbRubik|500||on|||||\u00a0\u00bb header_3_text_color=\u00a0\u00bb#f58233&Prime; header_3_font_size=\u00a0\u00bb19px\u00a0\u00bb header_3_letter_spacing=\u00a0\u00bb2px\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb\u00a0\u00bb text_font_size_phone=\u00a0\u00bb14px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_text_align_tablet=\u00a0\u00bb\u00a0\u00bb header_text_align_phone=\u00a0\u00bbcenter\u00a0\u00bb header_text_align_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_2_text_align_tablet=\u00a0\u00bb\u00a0\u00bb header_2_text_align_phone=\u00a0\u00bbleft\u00a0\u00bb header_2_text_align_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_2_font_size_tablet=\u00a0\u00bb32px\u00a0\u00bb header_2_font_size_phone=\u00a0\u00bb21px\u00a0\u00bb header_2_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_2_line_height_tablet=\u00a0\u00bb1.5em\u00a0\u00bb header_2_line_height_phone=\u00a0\u00bb0.8em\u00a0\u00bb header_2_line_height_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_3_text_align_tablet=\u00a0\u00bb\u00a0\u00bb header_3_text_align_phone=\u00a0\u00bbleft\u00a0\u00bb header_3_text_align_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_3_font_size_tablet=\u00a0\u00bb19px\u00a0\u00bb header_3_font_size_phone=\u00a0\u00bb17px\u00a0\u00bb header_3_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3>meilleurs endroits \u00e0 visiter en Bulgarie<\/h3>\n<h2>Bourgas<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb2_3,1_3&Prime; custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; custom_margin=\u00a0\u00bb-50px||||false|false\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb\u00a0\u00bb custom_padding_phone=\u00a0\u00bb15px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb2_3&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.25.1&Prime; text_font=\u00a0\u00bbPoppins|300|||||||\u00a0\u00bb text_font_size=\u00a0\u00bb16px\u00a0\u00bb text_line_height=\u00a0\u00bb2em\u00a0\u00bb text_orientation=\u00a0\u00bbjustified\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb\u00a0\u00bb text_font_size_phone=\u00a0\u00bb16px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<a href=\"https:\/\/goo.gl\/maps\/jv13utUZdJFS1kGs8\" target=\"_blank\" rel=\"noopener\">Bourgas<\/a> est la deuxi\u00e8me plus grande ville de la c\u00f4te bulgare de la mer Noire et la quatri\u00e8me de Bulgarie apr\u00e8s Sofia, Plovdiv et Varna. De plus, Bourgas n\u2019a commenc\u00e9 \u00e0 se d\u00e9velopper activement qu\u2019au XXe si\u00e8cle.<\/p>\n<p>On d\u00e9couvrit alors que la baie \u00e9tait une grande protectrice pour les industries commerciales et la marine. Il n\u2019est donc pas surprenant qu\u2019il y ait un grand centre industriel au c\u0153ur de la ville. Cependant, le front de mer principal est tr\u00e8s bien entretenu et les plages restent calmes. Il existe un certain nombre de bons restaurants et d&rsquo;h\u00e9bergements dans cette r\u00e9gion. De plus, des journ\u00e9es loin de la mer peuvent \u00eatre consacr\u00e9es \u00e0 la d\u00e9couverte des lacs.[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/soeasytravelinsurance.com\/wp-content\/uploads\/2022\/05\/burgas.jpg\u00a0\u00bb alt=\u00a0\u00bbBulgaria Travel Insurance\u00a0\u00bb title_text=\u00a0\u00bbBulgaria Travel Insurance\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb90%\u00a0\u00bb width_tablet=\u00a0\u00bb\u00a0\u00bb width_phone=\u00a0\u00bb\u00a0\u00bb width_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb admin_label=\u00a0\u00bbAbout\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.4&Prime; custom_margin_tablet=\u00a0\u00bb\u00a0\u00bb custom_margin_phone=\u00a0\u00bb1px||||false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_padding=\u00a0\u00bb16px||0px|||\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb\u00a0\u00bb custom_padding_phone=\u00a0\u00bb9px||5px||false|false\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.16&Prime; custom_margin_tablet=\u00a0\u00bb\u00a0\u00bb custom_margin_phone=\u00a0\u00bb20px||||false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.25.1&Prime; text_font=\u00a0\u00bb||||||||\u00a0\u00bb text_font_size=\u00a0\u00bb15px\u00a0\u00bb text_line_height=\u00a0\u00bb2em\u00a0\u00bb header_font=\u00a0\u00bb||||||||\u00a0\u00bb header_2_font=\u00a0\u00bbMontserrat|800|||||||\u00a0\u00bb header_2_font_size=\u00a0\u00bb27px\u00a0\u00bb header_2_line_height=\u00a0\u00bb1.5em\u00a0\u00bb header_3_font=\u00a0\u00bbRubik|500||on|||||\u00a0\u00bb header_3_text_color=\u00a0\u00bb#f58233&Prime; header_3_font_size=\u00a0\u00bb19px\u00a0\u00bb header_3_letter_spacing=\u00a0\u00bb2px\u00a0\u00bb max_width=\u00a0\u00bb500px\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb\u00a0\u00bb text_font_size_phone=\u00a0\u00bb14px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_text_align_tablet=\u00a0\u00bb\u00a0\u00bb header_text_align_phone=\u00a0\u00bbcenter\u00a0\u00bb header_text_align_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_2_text_align_tablet=\u00a0\u00bb\u00a0\u00bb header_2_text_align_phone=\u00a0\u00bbleft\u00a0\u00bb header_2_text_align_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_2_font_size_tablet=\u00a0\u00bb32px\u00a0\u00bb header_2_font_size_phone=\u00a0\u00bb21px\u00a0\u00bb header_2_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_2_line_height_tablet=\u00a0\u00bb1.5em\u00a0\u00bb header_2_line_height_phone=\u00a0\u00bb0.8em\u00a0\u00bb header_2_line_height_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_3_text_align_tablet=\u00a0\u00bb\u00a0\u00bb header_3_text_align_phone=\u00a0\u00bbleft\u00a0\u00bb header_3_text_align_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_3_font_size_tablet=\u00a0\u00bb19px\u00a0\u00bb header_3_font_size_phone=\u00a0\u00bb17px\u00a0\u00bb header_3_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>Bansko<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb2_3,1_3&Prime; custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; custom_margin=\u00a0\u00bb-50px||||false|false\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb\u00a0\u00bb custom_padding_phone=\u00a0\u00bb15px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb2_3&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.25.1&Prime; text_font=\u00a0\u00bbPoppins|300|||||||\u00a0\u00bb text_font_size=\u00a0\u00bb16px\u00a0\u00bb text_line_height=\u00a0\u00bb2em\u00a0\u00bb text_orientation=\u00a0\u00bbjustified\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb\u00a0\u00bb text_font_size_phone=\u00a0\u00bb16px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<a href=\"https:\/\/goo.gl\/maps\/4mMhFp7dLwtv9vbE7\" target=\"_blank\" rel=\"noopener\">Bansko<\/a> est une ville du sud-ouest de la Bulgarie, situ\u00e9e au pied des montagnes du Pirin, \u00e0 une altitude de 1 200 m au-dessus du niveau de la mer. La ville de Bansko est r\u00e9put\u00e9e pour \u00eatre la Mecque du ski en Bulgarie.<\/p>\n<p>La station de ski de Bansko est \u00e9galement reconnue pour avoir la plus longue saison de ski de Bulgarie. Elle rivalise r\u00e9guli\u00e8rement avec les stations fran\u00e7aises et suisses pour son ski de haute qualit\u00e9, \u00e0 des prix inf\u00e9rieurs \u00e0 ceux des Alpes. La station et la ville elle-m\u00eame comptent d&rsquo;innombrables restaurants apr\u00e8s-ski et lieux de vie nocturne, ainsi que des spas de classe mondiale pour se d\u00e9tendre lorsque les visiteurs ne d\u00e9valent pas les pistes. Chaque ann\u00e9e, la ville organise le festival de jazz de Bansko, qui attire des visiteurs internationaux et des artistes bulgares c\u00e9l\u00e8bres.[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/soeasytravelinsurance.com\/wp-content\/uploads\/2022\/05\/Bansko_in_the_winter_01-scaled.jpg\u00a0\u00bb alt=\u00a0\u00bbBulgaria Travel Insurance\u00a0\u00bb title_text=\u00a0\u00bbBulgaria Travel Insurance\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb90%\u00a0\u00bb width_tablet=\u00a0\u00bb\u00a0\u00bb width_phone=\u00a0\u00bb\u00a0\u00bb width_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb||50px|||\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb||50px|||\u00a0\u00bb custom_padding_phone=\u00a0\u00bb||20px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row disabled_on=\u00a0\u00bbon|on|on\u00a0\u00bb _builder_version=\u00a0\u00bb4.21.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb max_width=\u00a0\u00bb2002px\u00a0\u00bb custom_padding=\u00a0\u00bb||19px|||\u00a0\u00bb disabled=\u00a0\u00bbon\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_divider color=\u00a0\u00bb#d7dce1&Prime; divider_weight=\u00a0\u00bb1px\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb max_width=\u00a0\u00bb100%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row disabled_on=\u00a0\u00bbon|on|on\u00a0\u00bb _builder_version=\u00a0\u00bb4.21.0&Prime; custom_margin_tablet=\u00a0\u00bb\u00a0\u00bb custom_margin_phone=\u00a0\u00bb20px||||false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_padding=\u00a0\u00bb||0px|||\u00a0\u00bb disabled=\u00a0\u00bbon\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.16&Prime; text_font=\u00a0\u00bb||||||||\u00a0\u00bb text_font_size=\u00a0\u00bb15px\u00a0\u00bb text_line_height=\u00a0\u00bb2em\u00a0\u00bb header_font=\u00a0\u00bb||||||||\u00a0\u00bb header_2_font=\u00a0\u00bbMontserrat|800|||||||\u00a0\u00bb header_2_text_align=\u00a0\u00bbcenter\u00a0\u00bb header_2_font_size=\u00a0\u00bb32px\u00a0\u00bb header_2_line_height=\u00a0\u00bb1.5em\u00a0\u00bb header_3_font=\u00a0\u00bbRubik|500||on|||||\u00a0\u00bb header_3_text_align=\u00a0\u00bbcenter\u00a0\u00bb header_3_text_color=\u00a0\u00bb#f58233&Prime; header_3_font_size=\u00a0\u00bb19px\u00a0\u00bb header_3_letter_spacing=\u00a0\u00bb2px\u00a0\u00bb max_width=\u00a0\u00bb500px\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb\u00a0\u00bb text_font_size_phone=\u00a0\u00bb14px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_text_align_tablet=\u00a0\u00bb\u00a0\u00bb header_text_align_phone=\u00a0\u00bbcenter\u00a0\u00bb header_text_align_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_2_text_align_tablet=\u00a0\u00bb\u00a0\u00bb header_2_text_align_phone=\u00a0\u00bbcenter\u00a0\u00bb header_2_text_align_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_2_font_size_tablet=\u00a0\u00bb32px\u00a0\u00bb header_2_font_size_phone=\u00a0\u00bb21px\u00a0\u00bb header_2_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_2_line_height_tablet=\u00a0\u00bb1.5em\u00a0\u00bb header_2_line_height_phone=\u00a0\u00bb0.8em\u00a0\u00bb header_2_line_height_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_3_text_align_tablet=\u00a0\u00bb\u00a0\u00bb header_3_text_align_phone=\u00a0\u00bbcenter\u00a0\u00bb header_3_text_align_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_3_font_size_tablet=\u00a0\u00bb19px\u00a0\u00bb header_3_font_size_phone=\u00a0\u00bb17px\u00a0\u00bb header_3_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3>Our travel blog<\/h3>\n<p>[\/et_pb_text][et_pb_blog fullwidth=\u00a0\u00bboff\u00a0\u00bb posts_number=\u00a0\u00bb3&Prime; include_categories=\u00a0\u00bb13&Prime; _builder_version=\u00a0\u00bb4.19.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_blog][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb max_width=\u00a0\u00bb2002px\u00a0\u00bb custom_padding=\u00a0\u00bb||19px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_divider color=\u00a0\u00bb#d7dce1&Prime; divider_weight=\u00a0\u00bb1px\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb max_width=\u00a0\u00bb100%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; make_equal=\u00a0\u00bbon\u00a0\u00bb use_custom_gutter=\u00a0\u00bbon\u00a0\u00bb gutter_width=\u00a0\u00bb2&Prime; specialty=\u00a0\u00bbon\u00a0\u00bb padding_right_1=\u00a0\u00bb12%\u00a0\u00bb padding_bottom_1=\u00a0\u00bb40px\u00a0\u00bb padding_top_bottom_link_1=\u00a0\u00bbfalse\u00a0\u00bb padding_left_right_link_1=\u00a0\u00bbfalse\u00a0\u00bb padding_1_tablet=\u00a0\u00bb|0px|0px||false|false\u00a0\u00bb padding_1_phone=\u00a0\u00bb|0px|||false|false\u00a0\u00bb padding_1_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb use_background_color_gradient=\u00a0\u00bbon\u00a0\u00bb background_color_gradient_type=\u00a0\u00bbcircular\u00a0\u00bb background_color_gradient_direction_radial=\u00a0\u00bbtop right\u00a0\u00bb background_color_gradient_stops=\u00a0\u00bbrgba(0,0,0,0.77) 10%|rgba(0,0,0,0.71) 100%\u00a0\u00bb background_color_gradient_overlays_image=\u00a0\u00bbon\u00a0\u00bb background_color_gradient_start=\u00a0\u00bbrgba(0,0,0,0.77)\u00a0\u00bb background_color_gradient_start_position=\u00a0\u00bb10%\u00a0\u00bb background_color_gradient_end=\u00a0\u00bbrgba(0,0,0,0.71)\u00a0\u00bb background_image=\u00a0\u00bbhttps:\/\/soeasytravelinsurance.com\/wp-content\/uploads\/2022\/04\/view-air-plane-wing-during-take-off-landing-1-scaled-1.jpg\u00a0\u00bb background_position=\u00a0\u00bbtop_center\u00a0\u00bb background_vertical_offset=\u00a0\u00bb42%\u00a0\u00bb custom_padding=\u00a0\u00bb36px||0px|||\u00a0\u00bb background_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb background_vertical_offset_phone=\u00a0\u00bb70%\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/soeasytravelinsurance.com\/wp-content\/uploads\/2022\/06\/logo-1-36.png\u00a0\u00bb alt=\u00a0\u00bbSoeasy Travel Insurance\u00a0\u00bb title_text=\u00a0\u00bbSoeasy Travel Insurance\u00a0\u00bb url=\u00a0\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoiaG9tZV91cmwiLCJzZXR0aW5ncyI6e319@\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.4&Prime; _dynamic_attributes=\u00a0\u00bburl\u00a0\u00bb _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb||||false|false\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb||60px||false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bboff|desktop\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.21.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bbPoppins|300|||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb text_line_height=\u00a0\u00bb1.6em\u00a0\u00bb header_3_font=\u00a0\u00bbMontserrat|700|||||||\u00a0\u00bb header_3_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb header_3_font_size=\u00a0\u00bb21px\u00a0\u00bb custom_margin=\u00a0\u00bb60px||30px||false|false\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb17px\u00a0\u00bb text_font_size_phone=\u00a0\u00bb16px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3>Assurance voyage<\/h3>\n<p>Assurance voyage, assurance voyage pour le visa Schengen, polices d&rsquo;assurance voyage unique et multi-voyages pour l&rsquo;Europe et le monde entier.[\/et_pb_text][et_pb_button button_url=\u00a0\u00bbhttps:\/\/my.soeasytravelinsurance.com\/login\u00a0\u00bb url_new_window=\u00a0\u00bbon\u00a0\u00bb button_text=\u00a0\u00bbLOGIN AGENT\u00a0\u00bb button_alignment=\u00a0\u00bbleft\u00a0\u00bb button_alignment_tablet=\u00a0\u00bbcenter\u00a0\u00bb button_alignment_last_edited=\u00a0\u00bboff|tablet\u00a0\u00bb _builder_version=\u00a0\u00bb4.21.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_size=\u00a0\u00bb17px\u00a0\u00bb button_text_color=\u00a0\u00bb#ffffff\u00a0\u00bb button_bg_color=\u00a0\u00bb#f58233&Prime; button_border_width=\u00a0\u00bb0px\u00a0\u00bb button_border_radius=\u00a0\u00bb5px\u00a0\u00bb button_letter_spacing=\u00a0\u00bb2px\u00a0\u00bb button_font=\u00a0\u00bbRoboto|700||on|||||\u00a0\u00bb button_icon=\u00a0\u00bb&#x45;||divi||400&Prime; button_on_hover=\u00a0\u00bboff\u00a0\u00bb custom_padding=\u00a0\u00bb7px|37px|7px|20px|true|false\u00a0\u00bb button_text_size_tablet=\u00a0\u00bb21px\u00a0\u00bb button_text_size_phone=\u00a0\u00bb15px\u00a0\u00bb button_text_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb button_bg_color_tablet=\u00a0\u00bb#f58233&Prime; button_bg_color_phone=\u00a0\u00bb#f58233&Prime; button_bg_color_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb button_border_radius_tablet=\u00a0\u00bb0px\u00a0\u00bb button_border_radius_phone=\u00a0\u00bb5px\u00a0\u00bb button_border_radius_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb button_border_radius__hover=\u00a0\u00bb5px\u00a0\u00bb button_border_radius__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb button_letter_spacing__hover=\u00a0\u00bb3px\u00a0\u00bb button_letter_spacing__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb][\/et_pb_button][et_pb_image src=\u00a0\u00bbhttps:\/\/soeasytravelinsurance.com\/wp-content\/uploads\/2025\/10\/google.jpg\u00a0\u00bb title_text=\u00a0\u00bbgoogle\u00a0\u00bb url=\u00a0\u00bbhttps:\/\/www.google.com\/search?sca_esv=99f1a6d769628b16&#038;rlz=1C1GCEA_enCY999CY999&#038;sxsrf=AE3TifPnPloy8Gy98t7WTUEFs6CU1_2uCg:1758795298326&#038;si=AMgyJEtREmoPL4P1I5IDCfuA8gybfVI2d5Uj7QMwYCZHKDZ-E10Q063rmjDeX2XWDlW7RMUktuOkEGxDgz6ZPpq_ffNAbD199S2iwoqZZvO6HMfw5lCjfGqqpqDIdtgmx9erEMengjgOLQqyyUbxjsZllOfy7b3zKw%3D%3D&#038;q=SoEasy+Travel+Insurance+Reviews&#038;sa=X&#038;ved=2ahUKEwin7PSH1_OPAxWdTqQEHXI0KkEQ0bkNegQIIhAD\u00a0\u00bb url_new_window=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb||||false|false\u00a0\u00bb border_radii=\u00a0\u00bbon|10px|10px|10px|10px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb][\/et_pb_image][et_pb_code _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_orientation=\u00a0\u00bbleft\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb max_width=\u00a0\u00bb100%\u00a0\u00bb custom_margin=\u00a0\u00bb||||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb||||false|false\u00a0\u00bb link_option_url=\u00a0\u00bbhttps:\/\/www.trustpilot.com\/review\/soeasytravelinsurance.com\u00a0\u00bb link_option_url_new_window=\u00a0\u00bbon\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb]<div class=\"gutensuite-reviewkit_fpln_mcts gutensuite-reviewkit_fpln_common\"><div class=\"gutensuite-reviewkit_fpln_inner_left\"><span class=\"review_us_one\">Excellent<\/span><div class=\"gutensuite-reviewkit_score\"><span class=\"gutensuite-reviewkit_orignal_rcount\">4.8<\/span><span class=\"gutensuite-reviewkit_out_of\"> out of 5<\/span><\/div><\/div><div class=\"gutensuite-reviewkit_fpln_inner_right\"><img decoding=\"async\" src=\"https:\/\/soeasytravelinsurance.com\/wp-content\/plugins\/gutensuite-reviewkit\/assets\/images\/single-star.svg\" alt=\"Trustpilot logo\"  style=\"width: 20px;\" \/><span class=\"place_name\"> Trustpilot<\/span><\/div><\/div>[\/et_pb_code][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _dynamic_attributes=\u00a0\u00bbcontent\u00a0\u00bb _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bbPoppins||||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb text_font_size=\u00a0\u00bb16px\u00a0\u00bb link_font=\u00a0\u00bbPoppins||||||||\u00a0\u00bb link_text_color=\u00a0\u00bb#f58233&Prime; link_font_size=\u00a0\u00bb16px\u00a0\u00bb width=\u00a0\u00bb200%\u00a0\u00bb width_tablet=\u00a0\u00bb200%\u00a0\u00bb width_phone=\u00a0\u00bb98%\u00a0\u00bb width_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb max_width=\u00a0\u00bb200%\u00a0\u00bb max_width_tablet=\u00a0\u00bb200%\u00a0\u00bb max_width_phone=\u00a0\u00bb99%\u00a0\u00bb max_width_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb custom_margin=\u00a0\u00bb100px||||false|false\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb100px||||false|false\u00a0\u00bb custom_margin_phone=\u00a0\u00bb100px||||false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;]@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoiY3VycmVudF9kYXRlIiwic2V0dGluZ3MiOnsiYmVmb3JlIjoiQ29weXJpZ2h0IMKpICIsImFmdGVyIjoiIFNvIEVhc3kgVHJhdmVsIEluc3VyYW5jZS4gPGEgaHJlZj1cImh0dHBzOi8vc29lYXN5dHJhdmVsaW5zdXJhbmNlLmNvbS9wcml2YWN5LXBvbGljeS9cIiB0YXJnZXQ9XCJfYmxhbmtcIiByZWw9XCJub29wZW5lclwiPlBvbGl0aXF1ZSBkZSBjb25maWRlbnRpYWxpdMOpPC9hPiAgSSA8YSBocmVmPVwiaHR0cHM6Ly9zb2Vhc3l0cmF2ZWxpbnN1cmFuY2UuY29tL3Rlcm1zLWFuZC1jb25kaXRpb25zL1wiIHRhcmdldD1cIl9ibGFua1wiIHJlbD1cIm5vb3BlbmVyXCI+Q29uZGl0aW9ucyBnw6luw6lyYWxlcyA8L2E+ICIsImRhdGVfZm9ybWF0IjoiY3VzdG9tIiwiY3VzdG9tX2RhdGVfZm9ybWF0IjoiWSJ9fQ==@[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; specialty_columns=\u00a0\u00bb2&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][\/et_pb_column][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Assurance voyage Bulgarie Lorsque vous voyagez \u00e0 l\u2019\u00e9tranger, il est essentiel d\u2019avoir la bonne assurance voyage pour garantir que votre voyage se d\u00e9roule en toute s\u00e9curit\u00e9 et sans stress. La Bulgarie propose une assurance voyage compl\u00e8te qui couvre divers risques et accidents pouvant survenir pendant votre voyage. Que vous envisagiez de voyager pour le plaisir [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":238937,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-template-blank.php","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","cybocfi_hide_featured_image":"","footnotes":""},"class_list":["post-256273","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Assurance voyage Bulgarie - SoEasy Travel Insurance<\/title>\n<meta name=\"description\" content=\"Assurance voyage Bulgarie avec une protection compl\u00e8te, des conseils de voyage et des conseils de s\u00e9curit\u00e9 pour une exp\u00e9rience inoubliable.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/soeasytravelinsurance.com\/bulgaria-travel-insurance\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Assurance voyage Bulgarie\" \/>\n<meta property=\"og:description\" content=\"Assurance voyage Bulgarie avec une protection compl\u00e8te, des conseils de voyage et des conseils de s\u00e9curit\u00e9 pour une exp\u00e9rience inoubliable.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/soeasytravelinsurance.com\/bulgaria-travel-insurance\/\" \/>\n<meta property=\"og:site_name\" content=\"SoEasy Travel Insurance\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-17T10:34:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/soeasytravelinsurance.com\/wp-content\/uploads\/2022\/05\/Bansko_in_the_winter_01-1024x683.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:description\" content=\"Assurance voyage Bulgarie avec une protection compl\u00e8te, des conseils de voyage et des conseils de s\u00e9curit\u00e9 pour une exp\u00e9rience inoubliable.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/soeasytravelinsurance.com\/wp-content\/uploads\/2022\/05\/Bansko_in_the_winter_01-1024x683.jpg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/soeasytravelinsurance.com\\\/bulgaria-travel-insurance\\\/\",\"url\":\"https:\\\/\\\/soeasytravelinsurance.com\\\/bulgaria-travel-insurance\\\/\",\"name\":\"Assurance voyage Bulgarie - SoEasy Travel Insurance\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/soeasytravelinsurance.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/soeasytravelinsurance.com\\\/bulgaria-travel-insurance\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/soeasytravelinsurance.com\\\/bulgaria-travel-insurance\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/soeasytravelinsurance.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Bansko_in_the_winter_01-scaled.jpg\",\"datePublished\":\"2022-04-18T10:30:19+00:00\",\"dateModified\":\"2025-12-17T10:34:44+00:00\",\"description\":\"Assurance voyage Bulgarie avec une protection compl\u00e8te, des conseils de voyage et des conseils de s\u00e9curit\u00e9 pour une exp\u00e9rience inoubliable.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/soeasytravelinsurance.com\\\/bulgaria-travel-insurance\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/soeasytravelinsurance.com\\\/bulgaria-travel-insurance\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/soeasytravelinsurance.com\\\/bulgaria-travel-insurance\\\/#primaryimage\",\"url\":\"https:\\\/\\\/soeasytravelinsurance.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Bansko_in_the_winter_01-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/soeasytravelinsurance.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Bansko_in_the_winter_01-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Bansko, Bulgaria\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/soeasytravelinsurance.com\\\/bulgaria-travel-insurance\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Travel Insurance\",\"item\":\"https:\\\/\\\/soeasytravelinsurance.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Assurance voyage Bulgarie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/soeasytravelinsurance.com\\\/#website\",\"url\":\"https:\\\/\\\/soeasytravelinsurance.com\\\/\",\"name\":\"SoEasy Travel Insurance\",\"description\":\"Whether it\u2019s a beach holiday with the family, a business trip, or a training trip away at SoEasy international travel Insurance, you can buy the best single trip travel medical insurance and multi-trip travel medical insurance online.\",\"publisher\":{\"@id\":\"https:\\\/\\\/soeasytravelinsurance.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/soeasytravelinsurance.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/soeasytravelinsurance.com\\\/#organization\",\"name\":\"So Easy Travel Insurance\",\"url\":\"https:\\\/\\\/soeasytravelinsurance.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/soeasytravelinsurance.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/soeasytravelinsurance.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo-5.png\",\"contentUrl\":\"https:\\\/\\\/soeasytravelinsurance.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo-5.png\",\"width\":210,\"height\":66,\"caption\":\"So Easy Travel Insurance\"},\"image\":{\"@id\":\"https:\\\/\\\/soeasytravelinsurance.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Assurance voyage Bulgarie - SoEasy Travel Insurance","description":"Assurance voyage Bulgarie avec une protection compl\u00e8te, des conseils de voyage et des conseils de s\u00e9curit\u00e9 pour une exp\u00e9rience inoubliable.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/soeasytravelinsurance.com\/bulgaria-travel-insurance\/","og_locale":"fr_FR","og_type":"article","og_title":"Assurance voyage Bulgarie","og_description":"Assurance voyage Bulgarie avec une protection compl\u00e8te, des conseils de voyage et des conseils de s\u00e9curit\u00e9 pour une exp\u00e9rience inoubliable.","og_url":"https:\/\/soeasytravelinsurance.com\/bulgaria-travel-insurance\/","og_site_name":"SoEasy Travel Insurance","article_modified_time":"2025-12-17T10:34:44+00:00","og_image":[{"url":"https:\/\/soeasytravelinsurance.com\/wp-content\/uploads\/2022\/05\/Bansko_in_the_winter_01-1024x683.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_description":"Assurance voyage Bulgarie avec une protection compl\u00e8te, des conseils de voyage et des conseils de s\u00e9curit\u00e9 pour une exp\u00e9rience inoubliable.","twitter_image":"https:\/\/soeasytravelinsurance.com\/wp-content\/uploads\/2022\/05\/Bansko_in_the_winter_01-1024x683.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/soeasytravelinsurance.com\/bulgaria-travel-insurance\/","url":"https:\/\/soeasytravelinsurance.com\/bulgaria-travel-insurance\/","name":"Assurance voyage Bulgarie - SoEasy Travel Insurance","isPartOf":{"@id":"https:\/\/soeasytravelinsurance.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/soeasytravelinsurance.com\/bulgaria-travel-insurance\/#primaryimage"},"image":{"@id":"https:\/\/soeasytravelinsurance.com\/bulgaria-travel-insurance\/#primaryimage"},"thumbnailUrl":"https:\/\/soeasytravelinsurance.com\/wp-content\/uploads\/2022\/05\/Bansko_in_the_winter_01-scaled.jpg","datePublished":"2022-04-18T10:30:19+00:00","dateModified":"2025-12-17T10:34:44+00:00","description":"Assurance voyage Bulgarie avec une protection compl\u00e8te, des conseils de voyage et des conseils de s\u00e9curit\u00e9 pour une exp\u00e9rience inoubliable.","breadcrumb":{"@id":"https:\/\/soeasytravelinsurance.com\/bulgaria-travel-insurance\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/soeasytravelinsurance.com\/bulgaria-travel-insurance\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/soeasytravelinsurance.com\/bulgaria-travel-insurance\/#primaryimage","url":"https:\/\/soeasytravelinsurance.com\/wp-content\/uploads\/2022\/05\/Bansko_in_the_winter_01-scaled.jpg","contentUrl":"https:\/\/soeasytravelinsurance.com\/wp-content\/uploads\/2022\/05\/Bansko_in_the_winter_01-scaled.jpg","width":2560,"height":1707,"caption":"Bansko, Bulgaria"},{"@type":"BreadcrumbList","@id":"https:\/\/soeasytravelinsurance.com\/bulgaria-travel-insurance\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Travel Insurance","item":"https:\/\/soeasytravelinsurance.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Assurance voyage Bulgarie"}]},{"@type":"WebSite","@id":"https:\/\/soeasytravelinsurance.com\/#website","url":"https:\/\/soeasytravelinsurance.com\/","name":"SoEasy Travel Insurance","description":"Whether it\u2019s a beach holiday with the family, a business trip, or a training trip away at SoEasy international travel Insurance, you can buy the best single trip travel medical insurance and multi-trip travel medical insurance online.","publisher":{"@id":"https:\/\/soeasytravelinsurance.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/soeasytravelinsurance.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/soeasytravelinsurance.com\/#organization","name":"So Easy Travel Insurance","url":"https:\/\/soeasytravelinsurance.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/soeasytravelinsurance.com\/#\/schema\/logo\/image\/","url":"https:\/\/soeasytravelinsurance.com\/wp-content\/uploads\/2022\/04\/logo-5.png","contentUrl":"https:\/\/soeasytravelinsurance.com\/wp-content\/uploads\/2022\/04\/logo-5.png","width":210,"height":66,"caption":"So Easy Travel Insurance"},"image":{"@id":"https:\/\/soeasytravelinsurance.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/soeasytravelinsurance.com\/fr\/wp-json\/wp\/v2\/pages\/256273","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/soeasytravelinsurance.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/soeasytravelinsurance.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/soeasytravelinsurance.com\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/soeasytravelinsurance.com\/fr\/wp-json\/wp\/v2\/comments?post=256273"}],"version-history":[{"count":1,"href":"https:\/\/soeasytravelinsurance.com\/fr\/wp-json\/wp\/v2\/pages\/256273\/revisions"}],"predecessor-version":[{"id":288444,"href":"https:\/\/soeasytravelinsurance.com\/fr\/wp-json\/wp\/v2\/pages\/256273\/revisions\/288444"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/soeasytravelinsurance.com\/fr\/wp-json\/wp\/v2\/media\/238937"}],"wp:attachment":[{"href":"https:\/\/soeasytravelinsurance.com\/fr\/wp-json\/wp\/v2\/media?parent=256273"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}