{"id":256707,"date":"2022-04-19T07:59:28","date_gmt":"2022-04-19T07:59:28","guid":{"rendered":"https:\/\/soeasytravelinsurance.com\/?page_id=256707"},"modified":"2025-12-18T12:16:24","modified_gmt":"2025-12-18T12:16:24","slug":"saint-martin-travel-insurance","status":"publish","type":"page","link":"https:\/\/soeasytravelinsurance.com\/fr\/saint-martin-travel-insurance\/","title":{"rendered":"Assurance voyage Saint Martin"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb admin_label=\u00a0\u00bbHero\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; use_background_color_gradient=\u00a0\u00bbon\u00a0\u00bb background_color_gradient_type=\u00a0\u00bbcircular\u00a0\u00bb background_color_gradient_direction_radial=\u00a0\u00bbtop right\u00a0\u00bb background_color_gradient_stops=\u00a0\u00bbrgba(0,0,0,0.32) 10%|rgba(0,0,0,0.32) 100%\u00a0\u00bb background_color_gradient_overlays_image=\u00a0\u00bbon\u00a0\u00bb background_color_gradient_start=\u00a0\u00bbrgba(0,0,0,0.32)\u00a0\u00bb background_color_gradient_start_position=\u00a0\u00bb10%\u00a0\u00bb background_color_gradient_end=\u00a0\u00bbrgba(0,0,0,0.32)\u00a0\u00bb background_image=\u00a0\u00bbhttps:\/\/soeasytravelinsurance.com\/wp-content\/uploads\/2022\/04\/view-air-plane-wing-during-take-off-landing-1-scaled-1.jpg\u00a0\u00bb background_position=\u00a0\u00bbtop_center\u00a0\u00bb background_vertical_offset=\u00a0\u00bb42%\u00a0\u00bb custom_padding=\u00a0\u00bb80px|0|150px||false|false\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb0|0|150px||false|false\u00a0\u00bb custom_padding_phone=\u00a0\u00bb0|0|40px||false|false\u00a0\u00bb background_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb background_vertical_offset_phone=\u00a0\u00bb70%\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row custom_padding_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color_gradient_direction=\u00a0\u00bb90deg\u00a0\u00bb background_color_gradient_start=\u00a0\u00bb#0C316B\u00a0\u00bb background_color_gradient_end=\u00a0\u00bb#081131&Prime; width_last_edited=\u00a0\u00bboff|desktop\u00a0\u00bb custom_padding=\u00a0\u00bb8px|0px|8px|0px|true|true\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb5px||5px||true|false\u00a0\u00bb custom_padding_phone=\u00a0\u00bb60px||||false|true\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_menu menu_id=\u00a0\u00bb11&Prime; active_link_color=\u00a0\u00bb#f58233&Prime; dropdown_menu_bg_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb dropdown_menu_line_color=\u00a0\u00bb#f58233&Prime; dropdown_menu_text_color=\u00a0\u00bb#000000&Prime; dropdown_menu_active_link_color=\u00a0\u00bb#f58233&Prime; mobile_menu_bg_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb mobile_menu_text_color=\u00a0\u00bb#000000&Prime; logo=\u00a0\u00bbhttps:\/\/soeasytravelinsurance.com\/wp-content\/uploads\/2022\/06\/logo-1-36.png\u00a0\u00bb logo_url=\u00a0\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoiaG9tZV91cmwiLCJzZXR0aW5ncyI6e319@\u00a0\u00bb logo_width=\u00a0\u00bb120%\u00a0\u00bb logo_max_width=\u00a0\u00bb260px\u00a0\u00bb logo_max_height=\u00a0\u00bb230px\u00a0\u00bb cart_icon_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb search_icon_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb menu_icon_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb mobile_menu_text_color_last_edited=\u00a0\u00bboff|desktop\u00a0\u00bb logo_max_width_tablet=\u00a0\u00bb260px\u00a0\u00bb logo_max_width_phone=\u00a0\u00bb350px\u00a0\u00bb logo_max_width_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.4&Prime; _dynamic_attributes=\u00a0\u00bblogo_url\u00a0\u00bb _module_preset=\u00a0\u00bbdefault\u00a0\u00bb menu_font=\u00a0\u00bbPoppins||||||||\u00a0\u00bb menu_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb menu_font_size=\u00a0\u00bb16px\u00a0\u00bb background_enable_color=\u00a0\u00bboff\u00a0\u00bb text_orientation=\u00a0\u00bbright\u00a0\u00bb width_last_edited=\u00a0\u00bboff|desktop\u00a0\u00bb custom_margin=\u00a0\u00bb||15px|||\u00a0\u00bb custom_padding=\u00a0\u00bb||0px||false|false\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb mobile_menu_text_color__hover_enabled=\u00a0\u00bboff|desktop\u00a0\u00bb][\/et_pb_menu][et_pb_code _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<script><!-- [et_pb_line_break_holder] -->(function($) { <!-- [et_pb_line_break_holder] -->    function setup_collapsible_submenus() {<!-- [et_pb_line_break_holder] -->        \/\/ mobile menu<!-- [et_pb_line_break_holder] -->        $('.mobile_nav .menu-item-has-children > a').after('<span class=\"menu-closed\"><\/span>');<!-- [et_pb_line_break_holder] -->        $('.mobile_nav .menu-item-has-children > a').each(function() {<!-- [et_pb_line_break_holder] -->            $(this).next().next('.sub-menu').toggleClass('hide',1000);<!-- [et_pb_line_break_holder] -->        });<!-- [et_pb_line_break_holder] -->        $('.mobile_nav .menu-item-has-children > a + span').on('click', function(event) {<!-- [et_pb_line_break_holder] -->            event.preventDefault();<!-- [et_pb_line_break_holder] -->            $(this).toggleClass('menu-open');<!-- [et_pb_line_break_holder] -->            $(this).next('.sub-menu').toggleClass('hide',1000);<!-- [et_pb_line_break_holder] -->        });<!-- [et_pb_line_break_holder] -->    }<!-- [et_pb_line_break_holder] -->    $(window).load(function() {<!-- [et_pb_line_break_holder] -->        setTimeout(function() {<!-- [et_pb_line_break_holder] -->            setup_collapsible_submenus();<!-- [et_pb_line_break_holder] -->        }, 700);<!-- [et_pb_line_break_holder] -->    });<!-- [et_pb_line_break_holder] -->})(jQuery);<!-- [et_pb_line_break_holder] --><\/script><!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] --><\/p>\n<style><!-- [et_pb_line_break_holder] -->\/*edit the Divi submenu*\/<!-- [et_pb_line_break_holder] -->.dp_header_v22.et_pb_menu .nav li ul {<!-- [et_pb_line_break_holder] -->margin-top:10px!important;<!-- [et_pb_line_break_holder] -->padding:0!important;<!-- [et_pb_line_break_holder] -->box-shadow: 0 5px 30px 5px rgb(69 79 91 \/ 20%);<!-- [et_pb_line_break_holder] -->border-top: none;<!-- [et_pb_line_break_holder] -->text-align:left;<!-- [et_pb_line_break_holder] -->border-radius:5px;<!-- [et_pb_line_break_holder] -->}<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->\/*add point on top of the Divi menu submenu dropdown*\/<!-- [et_pb_line_break_holder] -->.dp_header_v22 nav>ul>li>ul:after {<!-- [et_pb_line_break_holder] -->position: absolute;<!-- [et_pb_line_break_holder] -->left: 20%;<!-- [et_pb_line_break_holder] -->margin-left: -20px;<!-- [et_pb_line_break_holder] -->top: -14px;<!-- [et_pb_line_break_holder] -->width: 0;<!-- [et_pb_line_break_holder] -->height: 0;<!-- [et_pb_line_break_holder] -->content: '';<!-- [et_pb_line_break_holder] -->border-left: 15px solid transparent;<!-- [et_pb_line_break_holder] -->border-right: 15px solid transparent;<!-- [et_pb_line_break_holder] -->border-bottom: 15px solid #ffffff;<!-- [et_pb_line_break_holder] -->}<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->\/*edit the Divi submenu list items*\/<!-- [et_pb_line_break_holder] -->.dp_header_v22.et_pb_menu .nav li ul.sub-menu a {<!-- [et_pb_line_break_holder] -->padding:12px 0px !important; <!-- [et_pb_line_break_holder] -->}<!-- [et_pb_line_break_holder] -->  <!-- [et_pb_line_break_holder] -->\/*edit the Divi submenu list items*\/<!-- [et_pb_line_break_holder] -->.dp_header_v22.et_pb_menu .nav li ul.sub-menu a:hover {<!-- [et_pb_line_break_holder] -->background:transparent!important;<!-- [et_pb_line_break_holder] -->}<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->.dp_header_v22 .nav li li:not(:last-child) {<!-- [et_pb_line_break_holder] -->border-bottom: 1px solid rgb(0,0,0,0.1);<!-- [et_pb_line_break_holder] -->}<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->\/*change Divi hamburger menu to X*\/<!-- [et_pb_line_break_holder] -->.dp_header_v22 .mobile_nav.opened .mobile_menu_bar:before {<!-- [et_pb_line_break_holder] -->content: '\\4d';<!-- [et_pb_line_break_holder] -->}<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->\/*edit the Divi mobile menu*\/<!-- [et_pb_line_break_holder] -->.dp_header_v22 .et_mobile_menu{<!-- [et_pb_line_break_holder] -->margin-top:10px;<!-- [et_pb_line_break_holder] -->box-shadow: 0 5px 30px 5px rgb(69 79 91 \/ 20%);<!-- [et_pb_line_break_holder] -->border-radius:5px;<!-- [et_pb_line_break_holder] -->padding:0!important;<!-- [et_pb_line_break_holder] -->}<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->.dp_header_v22 .mobile_nav .menu-item-has-children > a {<!-- [et_pb_line_break_holder] -->background: transparent;<!-- [et_pb_line_break_holder] -->color: #000!important;<!-- [et_pb_line_break_holder] -->}<!-- [et_pb_line_break_holder] -->  <!-- [et_pb_line_break_holder] -->@media screen and (max-width: 980px){<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->.dp_header_v22 .et_pb_menu_inner_container {<!-- [et_pb_line_break_holder] -->    display: flex;<!-- [et_pb_line_break_holder] -->}<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->.dp_header_v22 .et_pb_menu__wrap {<!-- [et_pb_line_break_holder] -->    justify-content:flex-end!important;<!-- [et_pb_line_break_holder] -->}<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->}<!-- [et_pb_line_break_holder] -->  <!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->\/**** Divi Mobile Menu Collapse Effect ****\/<!-- [et_pb_line_break_holder] -->\/**** This hides the sub menu items on mobile ****\/<!-- [et_pb_line_break_holder] -->#page-container .mobile_nav li ul.hide {<!-- [et_pb_line_break_holder] -->display: none !important;<!-- [et_pb_line_break_holder] -->}<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->\/**** This adjusts the positioning and the background transparency of the parent menu item on mobile ****\/<!-- [et_pb_line_break_holder] -->#page-container .mobile_nav .menu-item-has-children {<!-- [et_pb_line_break_holder] -->position: relative;<!-- [et_pb_line_break_holder] -->}<!-- [et_pb_line_break_holder] -->#page-container .mobile_nav .menu-item-has-children > a {<!-- [et_pb_line_break_holder] -->background: transparent;<!-- [et_pb_line_break_holder] -->}<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->\/**** This styles the icon and moves it to the right ****\/<!-- [et_pb_line_break_holder] -->#page-container .mobile_nav .menu-item-has-children > a + span {<!-- [et_pb_line_break_holder] -->position: absolute;<!-- [et_pb_line_break_holder] -->right: 0;<!-- [et_pb_line_break_holder] -->top: 0;<!-- [et_pb_line_break_holder] -->padding: 10px 20px;<!-- [et_pb_line_break_holder] -->font-size: 20px;<!-- [et_pb_line_break_holder] -->font-weight: 700;<!-- [et_pb_line_break_holder] -->cursor: pointer;<!-- [et_pb_line_break_holder] -->z-index: 3;<!-- [et_pb_line_break_holder] -->}<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->\/**** Here you can swap out the actual icons ****\/<!-- [et_pb_line_break_holder] -->#page-container span.menu-closed:before {<!-- [et_pb_line_break_holder] -->content: \"\\4c\";<!-- [et_pb_line_break_holder] -->display: block;<!-- [et_pb_line_break_holder] -->color: #000;<!-- [et_pb_line_break_holder] -->font-size: 16px;<!-- [et_pb_line_break_holder] -->font-family: ETmodules;<!-- [et_pb_line_break_holder] -->}<!-- [et_pb_line_break_holder] -->#page-container span.menu-closed.menu-open:before {<!-- [et_pb_line_break_holder] -->content: \"\\4d\";<!-- [et_pb_line_break_holder] -->}<!-- [et_pb_line_break_holder] --><\/style>\n<p>[\/et_pb_code][\/et_pb_column][\/et_pb_row][et_pb_row custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; custom_margin=\u00a0\u00bb|||\u00a0\u00bb custom_padding=\u00a0\u00bb82px||||false|false\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb150px||||false|false\u00a0\u00bb custom_padding_phone=\u00a0\u00bb120px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; text_font=\u00a0\u00bbPoppins|300|||||||\u00a0\u00bb text_font_size=\u00a0\u00bb18px\u00a0\u00bb text_line_height=\u00a0\u00bb2em\u00a0\u00bb header_font=\u00a0\u00bbMontserrat|800|||||||\u00a0\u00bb header_font_size=\u00a0\u00bb54px\u00a0\u00bb header_line_height=\u00a0\u00bb1.4em\u00a0\u00bb background_layout=\u00a0\u00bbdark\u00a0\u00bb max_width=\u00a0\u00bb950px\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb\u00a0\u00bb text_font_size_phone=\u00a0\u00bb16px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_font_size_tablet=\u00a0\u00bb44px\u00a0\u00bb header_font_size_phone=\u00a0\u00bb24px\u00a0\u00bb header_font_size_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb header_line_height_tablet=\u00a0\u00bb1.4em\u00a0\u00bb header_line_height_phone=\u00a0\u00bb1.4em\u00a0\u00bb header_line_height_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h1>Assurance voyage Saint Martin<\/h1>\n<p>Saint Martin est une \u00eele carib\u00e9enne dynamique o\u00f9 l&rsquo;\u00e9l\u00e9gance fran\u00e7aise et le charme n\u00e9erlandais se marient \u00e0 merveille avec des eaux turquoise, des plages dor\u00e9es et une sc\u00e8ne culturelle dynamique. Que vous savouriez la cuisine gastronomique de Marigot, profitiez de la vie nocturne de Philipsburg, vous d\u00e9tendiez \u00e0 la Baie Orientale ou fassiez du shopping en duty-free, Saint Martin offre un parfait m\u00e9lange de d\u00e9tente et d&rsquo;excitation. Mais m\u00eame dans ce paradis tropical, voyager peut r\u00e9server des surprises ; l&rsquo; assurance voyage Saint Martin est donc un choix judicieux et essentiel. Urgences m\u00e9dicales, retards de vol, perte de bagages, annulations de voyage : notre couverture compl\u00e8te vous prot\u00e8ge \u00e0 chaque \u00e9tape. Avec des formules personnalisables, un service de r\u00e9clamation rapide et une assistance d&rsquo;urgence 24h\/24 et 7j\/7, l&rsquo; assurance voyage Saint Martin vous offre la tranquillit\u00e9 d&rsquo;esprit pour explorer librement votre destination. Profitez du meilleur des deux mondes, nous nous occupons des impr\u00e9vus.<\/p>\n<p>[\/et_pb_text][et_pb_button button_url=\u00a0\u00bbhttps:\/\/my.soeasytravelinsurance.com\/s\/UqGL\u00a0\u00bb url_new_window=\u00a0\u00bbon\u00a0\u00bb button_text=\u00a0\u00bbCOMMENCER UN DEVIS\u00a0\u00bb _builder_version=\u00a0\u00bb4.21.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_size=\u00a0\u00bb16px\u00a0\u00bb button_text_color=\u00a0\u00bb#ffffff\u00a0\u00bb button_bg_color=\u00a0\u00bb#f58233&Prime; button_border_width=\u00a0\u00bb0px\u00a0\u00bb button_border_radius=\u00a0\u00bb5px\u00a0\u00bb button_letter_spacing=\u00a0\u00bb2px\u00a0\u00bb button_font=\u00a0\u00bbRoboto|700||on|||||\u00a0\u00bb button_icon=\u00a0\u00bb&#x45;||divi||400&Prime; button_on_hover=\u00a0\u00bboff\u00a0\u00bb custom_padding=\u00a0\u00bb10px|42px|10px|25px|true|false\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb10px|15px|10px|15px|true|true\u00a0\u00bb custom_padding_phone=\u00a0\u00bb9px|31px|9px|13px|true|false\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb button_text_size_tablet=\u00a0\u00bb21px\u00a0\u00bb button_text_size_phone=\u00a0\u00bb15px\u00a0\u00bb button_text_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb button_bg_color_tablet=\u00a0\u00bb\u00a0\u00bb button_bg_color_phone=\u00a0\u00bb#f58233&Prime; button_bg_color_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb button_bg_enable_color_phone=\u00a0\u00bbon\u00a0\u00bb button_border_radius_tablet=\u00a0\u00bb0px\u00a0\u00bb button_border_radius_phone=\u00a0\u00bb5px\u00a0\u00bb button_border_radius_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb button_bg_color__hover=\u00a0\u00bbrgba(0,0,0,0)\u00a0\u00bb button_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_radius__hover=\u00a0\u00bb5px\u00a0\u00bb button_border_radius__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb button_letter_spacing__hover=\u00a0\u00bb3px\u00a0\u00bb button_letter_spacing__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb][\/et_pb_button][et_pb_image src=\u00a0\u00bbhttps:\/\/soeasytravelinsurance.com\/wp-content\/uploads\/2025\/10\/google.jpg\u00a0\u00bb title_text=\u00a0\u00bbgoogle\u00a0\u00bb url=\u00a0\u00bbhttps:\/\/www.google.com\/search?sca_esv=99f1a6d769628b16&#038;rlz=1C1GCEA_enCY999CY999&#038;sxsrf=AE3TifPnPloy8Gy98t7WTUEFs6CU1_2uCg:1758795298326&#038;si=AMgyJEtREmoPL4P1I5IDCfuA8gybfVI2d5Uj7QMwYCZHKDZ-E10Q063rmjDeX2XWDlW7RMUktuOkEGxDgz6ZPpq_ffNAbD199S2iwoqZZvO6HMfw5lCjfGqqpqDIdtgmx9erEMengjgOLQqyyUbxjsZllOfy7b3zKw%3D%3D&#038;q=SoEasy+Travel+Insurance+Reviews&#038;sa=X&#038;ved=2ahUKEwin7PSH1_OPAxWdTqQEHXI0KkEQ0bkNegQIIhAD\u00a0\u00bb url_new_window=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb||||false|false\u00a0\u00bb border_radii=\u00a0\u00bbon|10px|10px|10px|10px\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_code _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_orientation=\u00a0\u00bbleft\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb max_width=\u00a0\u00bb100%\u00a0\u00bb custom_margin=\u00a0\u00bb||||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb||||false|false\u00a0\u00bb link_option_url=\u00a0\u00bbhttps:\/\/www.trustpilot.com\/review\/soeasytravelinsurance.com\u00a0\u00bb link_option_url_new_window=\u00a0\u00bbon\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<div class=\"gutensuite-reviewkit_fpln_mcts gutensuite-reviewkit_fpln_common\"><div class=\"gutensuite-reviewkit_fpln_inner_left\"><span class=\"review_us_one\">Excellent<\/span><div class=\"gutensuite-reviewkit_score\"><span class=\"gutensuite-reviewkit_orignal_rcount\">4.8<\/span><span class=\"gutensuite-reviewkit_out_of\"> out of 5<\/span><\/div><\/div><div class=\"gutensuite-reviewkit_fpln_inner_right\"><img decoding=\"async\" src=\"https:\/\/soeasytravelinsurance.com\/wp-content\/plugins\/gutensuite-reviewkit\/assets\/images\/single-star.svg\" alt=\"Trustpilot logo\"  style=\"width: 20px;\" \/><span class=\"place_name\"> Trustpilot<\/span><\/div><\/div>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb admin_label=\u00a0\u00bbAbout\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; custom_margin_tablet=\u00a0\u00bb\u00a0\u00bb custom_margin_phone=\u00a0\u00bb1px||||false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_padding=\u00a0\u00bb50px||0px||false|false\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb\u00a0\u00bb custom_padding_phone=\u00a0\u00bb9px||5px||false|false\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.16&Prime; custom_margin_tablet=\u00a0\u00bb\u00a0\u00bb custom_margin_phone=\u00a0\u00bb0px|auto||auto|false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_padding=\u00a0\u00bb12px||0px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; text_font=\u00a0\u00bb||||||||\u00a0\u00bb text_font_size=\u00a0\u00bb15px\u00a0\u00bb text_line_height=\u00a0\u00bb2em\u00a0\u00bb header_font=\u00a0\u00bb||||||||\u00a0\u00bb header_2_font=\u00a0\u00bbMontserrat|800|||||||\u00a0\u00bb header_2_font_size=\u00a0\u00bb27px\u00a0\u00bb header_2_line_height=\u00a0\u00bb1.5em\u00a0\u00bb header_3_font=\u00a0\u00bbRubik|500||on|||||\u00a0\u00bb header_3_text_color=\u00a0\u00bb#f58233&Prime; header_3_font_size=\u00a0\u00bb19px\u00a0\u00bb header_3_letter_spacing=\u00a0\u00bb2px\u00a0\u00bb max_width=\u00a0\u00bb1602px\u00a0\u00bb custom_margin=\u00a0\u00bb||||false|false\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb\u00a0\u00bb text_font_size_phone=\u00a0\u00bb14px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_text_align_tablet=\u00a0\u00bb\u00a0\u00bb header_text_align_phone=\u00a0\u00bbcenter\u00a0\u00bb header_text_align_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_2_text_align_tablet=\u00a0\u00bb\u00a0\u00bb header_2_text_align_phone=\u00a0\u00bbleft\u00a0\u00bb header_2_text_align_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_2_font_size_tablet=\u00a0\u00bb32px\u00a0\u00bb header_2_font_size_phone=\u00a0\u00bb21px\u00a0\u00bb header_2_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_2_line_height_tablet=\u00a0\u00bb1.5em\u00a0\u00bb header_2_line_height_phone=\u00a0\u00bb0.8em\u00a0\u00bb header_2_line_height_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_3_text_align_tablet=\u00a0\u00bb\u00a0\u00bb header_3_text_align_phone=\u00a0\u00bbleft\u00a0\u00bb header_3_text_align_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_3_font_size_tablet=\u00a0\u00bb19px\u00a0\u00bb header_3_font_size_phone=\u00a0\u00bb17px\u00a0\u00bb header_3_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3><strong>Pourquoi avez-vous besoin d&rsquo;une assurance voyage Saint Martin ?<\/strong><\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; custom_margin=\u00a0\u00bb-50px||||false|false\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb\u00a0\u00bb custom_padding_phone=\u00a0\u00bb15px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; text_font=\u00a0\u00bbPoppins|300|||||||\u00a0\u00bb text_font_size=\u00a0\u00bb16px\u00a0\u00bb text_line_height=\u00a0\u00bb2em\u00a0\u00bb text_orientation=\u00a0\u00bbjustified\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb\u00a0\u00bb text_font_size_phone=\u00a0\u00bb16px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h4><b>Prot\u00e9ger votre sant\u00e9 \u00e0 l&rsquo;\u00e9tranger<\/b><\/h4>\n<p><span style=\"font-weight: 400;\">Les soins m\u00e9dicaux \u00e0 Saint-Martin sont de premier ordre, mais ils peuvent s&rsquo;av\u00e9rer co\u00fbteux pour les touristes sans assurance. Une maladie ou une blessure soudaine peut se transformer en un fardeau financier si vous n&rsquo;\u00eates pas pr\u00e9par\u00e9.<\/span><\/p>\n<h4><b>Couverture des retards de voyage impr\u00e9vus<\/b><\/h4>\n<p><span style=\"font-weight: 400;\">Les retards et annulations de vol peuvent perturber votre itin\u00e9raire et vous co\u00fbter plus cher. Une assurance voyage vous aide \u00e0 couvrir ces d\u00e9penses impr\u00e9vues.<\/span><\/p>\n<h4><b>Protection contre la perte ou le vol d&rsquo;effets personnels<\/b><\/h4>\n<p><span style=\"font-weight: 400;\">La perte de bagages ou le vol d&rsquo;objets peuvent g\u00e2cher votre voyage. Avec une assurance voyage Saint Martin, vous pouvez r\u00e9cup\u00e9rer une partie de vos pertes financi\u00e8res et profiter \u00e0 nouveau de vos vacances.<\/span>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb admin_label=\u00a0\u00bbAbout\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.4&Prime; custom_margin_tablet=\u00a0\u00bb\u00a0\u00bb custom_margin_phone=\u00a0\u00bb1px||||false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_padding=\u00a0\u00bb16px||0px|||\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb\u00a0\u00bb custom_padding_phone=\u00a0\u00bb9px||5px||false|false\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.27.4&Prime; custom_margin_tablet=\u00a0\u00bb\u00a0\u00bb custom_margin_phone=\u00a0\u00bb0px|auto||auto|false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_padding=\u00a0\u00bb12px||0px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; text_font=\u00a0\u00bb||||||||\u00a0\u00bb text_font_size=\u00a0\u00bb15px\u00a0\u00bb text_line_height=\u00a0\u00bb2em\u00a0\u00bb header_font=\u00a0\u00bb||||||||\u00a0\u00bb header_2_font=\u00a0\u00bbMontserrat|800|||||||\u00a0\u00bb header_2_font_size=\u00a0\u00bb27px\u00a0\u00bb header_2_line_height=\u00a0\u00bb1.5em\u00a0\u00bb header_3_font=\u00a0\u00bbRubik|500||on|||||\u00a0\u00bb header_3_text_color=\u00a0\u00bb#f58233&Prime; header_3_font_size=\u00a0\u00bb19px\u00a0\u00bb header_3_letter_spacing=\u00a0\u00bb2px\u00a0\u00bb max_width=\u00a0\u00bb1602px\u00a0\u00bb custom_margin=\u00a0\u00bb||||false|false\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb\u00a0\u00bb text_font_size_phone=\u00a0\u00bb14px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_text_align_tablet=\u00a0\u00bb\u00a0\u00bb header_text_align_phone=\u00a0\u00bbcenter\u00a0\u00bb header_text_align_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_2_text_align_tablet=\u00a0\u00bb\u00a0\u00bb header_2_text_align_phone=\u00a0\u00bbleft\u00a0\u00bb header_2_text_align_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_2_font_size_tablet=\u00a0\u00bb32px\u00a0\u00bb header_2_font_size_phone=\u00a0\u00bb21px\u00a0\u00bb header_2_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_2_line_height_tablet=\u00a0\u00bb1.5em\u00a0\u00bb header_2_line_height_phone=\u00a0\u00bb0.8em\u00a0\u00bb header_2_line_height_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_3_text_align_tablet=\u00a0\u00bb\u00a0\u00bb header_3_text_align_phone=\u00a0\u00bbleft\u00a0\u00bb header_3_text_align_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_3_font_size_tablet=\u00a0\u00bb19px\u00a0\u00bb header_3_font_size_phone=\u00a0\u00bb17px\u00a0\u00bb header_3_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3><strong>Types de r\u00e9gimes d&rsquo; assurance voyage pour Saint Martin<\/strong><\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; custom_margin=\u00a0\u00bb-50px||||false|false\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb\u00a0\u00bb custom_padding_phone=\u00a0\u00bb15px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; text_font=\u00a0\u00bbPoppins|300|||||||\u00a0\u00bb text_font_size=\u00a0\u00bb16px\u00a0\u00bb text_line_height=\u00a0\u00bb2em\u00a0\u00bb text_orientation=\u00a0\u00bbjustified\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb\u00a0\u00bb text_font_size_phone=\u00a0\u00bb16px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h4><b>Assurance voyage aller simple<\/b><\/h4>\n<p><span style=\"font-weight: 400;\">Id\u00e9ale pour les voyageurs ponctuels, cette formule offre une couverture pour toute la dur\u00e9e de votre voyage.<\/span><\/p>\n<h4><b>Assurance voyage multi-voyages<\/b><\/h4>\n<p><span style=\"font-weight: 400;\">Les grands voyageurs peuvent b\u00e9n\u00e9ficier de cette formule, offrant une couverture pour plusieurs voyages au cours d&rsquo;une m\u00eame ann\u00e9e.<\/span><\/p>\n<h4><b>Assurance voyage \u00e9tudiant<\/b><\/h4>\n<p><span style=\"font-weight: 400;\">Id\u00e9ale pour les \u00e9tudiants en stage ou en formation \u00e0 l&rsquo;\u00e9tranger, elle couvre les frais de scolarit\u00e9, les soins de sant\u00e9 et les urgences de voyage.<\/span>[\/et_pb_text][et_pb_button button_url=\u00a0\u00bbhttps:\/\/my.soeasytravelinsurance.com\/travel-insurance\/details\u00a0\u00bb url_new_window=\u00a0\u00bbon\u00a0\u00bb button_text=\u00a0\u00bbAPPRENDRE ENCORE PLUS\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_size=\u00a0\u00bb16px\u00a0\u00bb button_text_color=\u00a0\u00bb#ffffff\u00a0\u00bb button_bg_color=\u00a0\u00bb#f58233&Prime; button_border_width=\u00a0\u00bb0px\u00a0\u00bb button_border_radius=\u00a0\u00bb5px\u00a0\u00bb button_letter_spacing=\u00a0\u00bb2px\u00a0\u00bb button_font=\u00a0\u00bbRoboto|700||on|||||\u00a0\u00bb button_icon=\u00a0\u00bb&#x45;||divi||400&Prime; button_on_hover=\u00a0\u00bboff\u00a0\u00bb custom_padding=\u00a0\u00bb10px|42px|10px|25px|true|false\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb10px|15px|10px|15px|true|true\u00a0\u00bb custom_padding_phone=\u00a0\u00bb9px|31px|9px|13px|true|false\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb button_text_size_tablet=\u00a0\u00bb21px\u00a0\u00bb button_text_size_phone=\u00a0\u00bb15px\u00a0\u00bb button_text_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb button_bg_color_tablet=\u00a0\u00bb\u00a0\u00bb button_bg_color_phone=\u00a0\u00bb#f58233&Prime; button_bg_color_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb button_bg_enable_color_phone=\u00a0\u00bbon\u00a0\u00bb button_border_radius_tablet=\u00a0\u00bb0px\u00a0\u00bb button_border_radius_phone=\u00a0\u00bb5px\u00a0\u00bb button_border_radius_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb button_bg_color__hover=\u00a0\u00bbrgba(0,0,0,0)\u00a0\u00bb button_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_radius__hover=\u00a0\u00bb5px\u00a0\u00bb button_border_radius__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb button_letter_spacing__hover=\u00a0\u00bb3px\u00a0\u00bb button_letter_spacing__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb admin_label=\u00a0\u00bbAbout\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.4&Prime; custom_margin_tablet=\u00a0\u00bb\u00a0\u00bb custom_margin_phone=\u00a0\u00bb1px||||false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_padding=\u00a0\u00bb16px||0px|||\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb\u00a0\u00bb custom_padding_phone=\u00a0\u00bb9px||5px||false|false\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.16&Prime; custom_margin_tablet=\u00a0\u00bb\u00a0\u00bb custom_margin_phone=\u00a0\u00bb0px|auto||auto|false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_padding=\u00a0\u00bb12px||0px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; text_font=\u00a0\u00bb||||||||\u00a0\u00bb text_font_size=\u00a0\u00bb15px\u00a0\u00bb text_line_height=\u00a0\u00bb2em\u00a0\u00bb header_font=\u00a0\u00bb||||||||\u00a0\u00bb header_2_font=\u00a0\u00bbMontserrat|800|||||||\u00a0\u00bb header_2_font_size=\u00a0\u00bb27px\u00a0\u00bb header_2_line_height=\u00a0\u00bb1.5em\u00a0\u00bb header_3_font=\u00a0\u00bbRubik|500||on|||||\u00a0\u00bb header_3_text_color=\u00a0\u00bb#f58233&Prime; header_3_font_size=\u00a0\u00bb19px\u00a0\u00bb header_3_letter_spacing=\u00a0\u00bb2px\u00a0\u00bb max_width=\u00a0\u00bb1602px\u00a0\u00bb custom_margin=\u00a0\u00bb||||false|false\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb\u00a0\u00bb text_font_size_phone=\u00a0\u00bb14px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_text_align_tablet=\u00a0\u00bb\u00a0\u00bb header_text_align_phone=\u00a0\u00bbcenter\u00a0\u00bb header_text_align_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_2_text_align_tablet=\u00a0\u00bb\u00a0\u00bb header_2_text_align_phone=\u00a0\u00bbleft\u00a0\u00bb header_2_text_align_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_2_font_size_tablet=\u00a0\u00bb32px\u00a0\u00bb header_2_font_size_phone=\u00a0\u00bb21px\u00a0\u00bb header_2_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_2_line_height_tablet=\u00a0\u00bb1.5em\u00a0\u00bb header_2_line_height_phone=\u00a0\u00bb0.8em\u00a0\u00bb header_2_line_height_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_3_text_align_tablet=\u00a0\u00bb\u00a0\u00bb header_3_text_align_phone=\u00a0\u00bbleft\u00a0\u00bb header_3_text_align_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_3_font_size_tablet=\u00a0\u00bb19px\u00a0\u00bb header_3_font_size_phone=\u00a0\u00bb17px\u00a0\u00bb header_3_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3><strong>Comprendre les options de couverture<\/strong><\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; custom_margin=\u00a0\u00bb-50px||||false|false\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb\u00a0\u00bb custom_padding_phone=\u00a0\u00bb15px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; text_font=\u00a0\u00bbPoppins|300|||||||\u00a0\u00bb text_font_size=\u00a0\u00bb16px\u00a0\u00bb text_line_height=\u00a0\u00bb2em\u00a0\u00bb text_orientation=\u00a0\u00bbjustified\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb\u00a0\u00bb text_font_size_phone=\u00a0\u00bb16px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h4><b>Assurance m\u00e9dicale et d&rsquo;urgence<\/b><\/h4>\n<p><span style=\"font-weight: 400;\">Cette couverture est au c\u0153ur de la plupart des assurances voyage et couvre l&rsquo;hospitalisation, les consultations m\u00e9dicales et les \u00e9vacuations d&rsquo;urgence.<\/span><\/p>\n<h4><b>Assurance annulation et interruption de voyage<\/b><\/h4>\n<p><span style=\"font-weight: 400;\">Si vous devez annuler ou interrompre votre voyage, cette couverture rembourse les frais non remboursables.<\/span><\/p>\n<h4><b>Assurance responsabilit\u00e9 civile<\/b><\/h4>\n<p><span style=\"font-weight: 400;\">Vous prot\u00e8ge en cas de dommages mat\u00e9riels ou de blessures corporelles accidentelles pendant votre voyage.<\/span>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb admin_label=\u00a0\u00bbAbout\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.4&Prime; custom_margin_tablet=\u00a0\u00bb\u00a0\u00bb custom_margin_phone=\u00a0\u00bb1px||||false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_padding=\u00a0\u00bb16px||0px|||\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb\u00a0\u00bb custom_padding_phone=\u00a0\u00bb9px||5px||false|false\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.16&Prime; custom_margin_tablet=\u00a0\u00bb\u00a0\u00bb custom_margin_phone=\u00a0\u00bb0px|auto||auto|false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_padding=\u00a0\u00bb12px||0px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; text_font=\u00a0\u00bb||||||||\u00a0\u00bb text_font_size=\u00a0\u00bb15px\u00a0\u00bb text_line_height=\u00a0\u00bb2em\u00a0\u00bb header_font=\u00a0\u00bb||||||||\u00a0\u00bb header_2_font=\u00a0\u00bbMontserrat|800|||||||\u00a0\u00bb header_2_font_size=\u00a0\u00bb27px\u00a0\u00bb header_2_line_height=\u00a0\u00bb1.5em\u00a0\u00bb header_3_font=\u00a0\u00bbRubik|500||on|||||\u00a0\u00bb header_3_text_color=\u00a0\u00bb#f58233&Prime; header_3_font_size=\u00a0\u00bb19px\u00a0\u00bb header_3_letter_spacing=\u00a0\u00bb2px\u00a0\u00bb max_width=\u00a0\u00bb1602px\u00a0\u00bb custom_margin=\u00a0\u00bb||||false|false\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb\u00a0\u00bb text_font_size_phone=\u00a0\u00bb14px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_text_align_tablet=\u00a0\u00bb\u00a0\u00bb header_text_align_phone=\u00a0\u00bbcenter\u00a0\u00bb header_text_align_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_2_text_align_tablet=\u00a0\u00bb\u00a0\u00bb header_2_text_align_phone=\u00a0\u00bbleft\u00a0\u00bb header_2_text_align_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_2_font_size_tablet=\u00a0\u00bb32px\u00a0\u00bb header_2_font_size_phone=\u00a0\u00bb21px\u00a0\u00bb header_2_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_2_line_height_tablet=\u00a0\u00bb1.5em\u00a0\u00bb header_2_line_height_phone=\u00a0\u00bb0.8em\u00a0\u00bb header_2_line_height_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_3_text_align_tablet=\u00a0\u00bb\u00a0\u00bb header_3_text_align_phone=\u00a0\u00bbleft\u00a0\u00bb header_3_text_align_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_3_font_size_tablet=\u00a0\u00bb19px\u00a0\u00bb header_3_font_size_phone=\u00a0\u00bb17px\u00a0\u00bb header_3_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3><strong>Choisir le bon fournisseur d&rsquo;assurance voyage<\/strong><\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; custom_margin=\u00a0\u00bb-50px||||false|false\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb\u00a0\u00bb custom_padding_phone=\u00a0\u00bb15px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; text_font=\u00a0\u00bbPoppins|300|||||||\u00a0\u00bb text_font_size=\u00a0\u00bb16px\u00a0\u00bb text_line_height=\u00a0\u00bb2em\u00a0\u00bb text_orientation=\u00a0\u00bbjustified\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb\u00a0\u00bb text_font_size_phone=\u00a0\u00bb16px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h4><b>Facteurs cl\u00e9s \u00e0 prendre en compte<\/b><\/h4>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Options de couverture<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Avis clients<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Efficacit\u00e9 du processus de r\u00e9clamation<\/span><\/li>\n<\/ul>\n<h4><b>Compagnies d&rsquo;assurance voyage populaires \u00e0 Saint Martin<\/b><\/h4>\n<p><span style=\"font-weight: 400;\">Des noms comme Allianz, AXA et \u00ab So Easy Travel Insurance \u00bb sont reconnus par les voyageurs du monde entier.<\/span><\/p>\n<p>[\/et_pb_text][et_pb_button button_url=\u00a0\u00bbhttps:\/\/my.soeasytravelinsurance.com\/travel-insurance\/details\u00a0\u00bb url_new_window=\u00a0\u00bbon\u00a0\u00bb button_text=\u00a0\u00bbACHETEZ MAINTENANT\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_size=\u00a0\u00bb16px\u00a0\u00bb button_text_color=\u00a0\u00bb#ffffff\u00a0\u00bb button_bg_color=\u00a0\u00bb#f58233&Prime; button_border_width=\u00a0\u00bb0px\u00a0\u00bb button_border_radius=\u00a0\u00bb5px\u00a0\u00bb button_letter_spacing=\u00a0\u00bb2px\u00a0\u00bb button_font=\u00a0\u00bbRoboto|700||on|||||\u00a0\u00bb button_icon=\u00a0\u00bb&#x45;||divi||400&Prime; button_on_hover=\u00a0\u00bboff\u00a0\u00bb custom_padding=\u00a0\u00bb10px|42px|10px|25px|true|false\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb10px|15px|10px|15px|true|true\u00a0\u00bb custom_padding_phone=\u00a0\u00bb9px|31px|9px|13px|true|false\u00a0\u00bb custom_padding_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb button_text_size_tablet=\u00a0\u00bb21px\u00a0\u00bb button_text_size_phone=\u00a0\u00bb15px\u00a0\u00bb button_text_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb button_bg_color_tablet=\u00a0\u00bb\u00a0\u00bb button_bg_color_phone=\u00a0\u00bb#f58233&Prime; button_bg_color_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb button_bg_enable_color_phone=\u00a0\u00bbon\u00a0\u00bb button_border_radius_tablet=\u00a0\u00bb0px\u00a0\u00bb button_border_radius_phone=\u00a0\u00bb5px\u00a0\u00bb button_border_radius_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb button_bg_color__hover=\u00a0\u00bbrgba(0,0,0,0)\u00a0\u00bb button_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_border_radius__hover=\u00a0\u00bb5px\u00a0\u00bb button_border_radius__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb button_letter_spacing__hover=\u00a0\u00bb3px\u00a0\u00bb button_letter_spacing__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb admin_label=\u00a0\u00bbAbout\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.4&Prime; custom_margin_tablet=\u00a0\u00bb\u00a0\u00bb custom_margin_phone=\u00a0\u00bb1px||||false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_padding=\u00a0\u00bb16px||0px|||\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb\u00a0\u00bb custom_padding_phone=\u00a0\u00bb9px||5px||false|false\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.16&Prime; custom_margin_tablet=\u00a0\u00bb\u00a0\u00bb custom_margin_phone=\u00a0\u00bb0px|auto||auto|false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_padding=\u00a0\u00bb12px||0px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; text_font=\u00a0\u00bb||||||||\u00a0\u00bb text_font_size=\u00a0\u00bb15px\u00a0\u00bb text_line_height=\u00a0\u00bb2em\u00a0\u00bb header_font=\u00a0\u00bb||||||||\u00a0\u00bb header_2_font=\u00a0\u00bbMontserrat|800|||||||\u00a0\u00bb header_2_font_size=\u00a0\u00bb27px\u00a0\u00bb header_2_line_height=\u00a0\u00bb1.5em\u00a0\u00bb header_3_font=\u00a0\u00bbRubik|500||on|||||\u00a0\u00bb header_3_text_color=\u00a0\u00bb#f58233&Prime; header_3_font_size=\u00a0\u00bb19px\u00a0\u00bb header_3_letter_spacing=\u00a0\u00bb2px\u00a0\u00bb max_width=\u00a0\u00bb600px\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb\u00a0\u00bb text_font_size_phone=\u00a0\u00bb14px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_text_align_tablet=\u00a0\u00bb\u00a0\u00bb header_text_align_phone=\u00a0\u00bbcenter\u00a0\u00bb header_text_align_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_2_text_align_tablet=\u00a0\u00bb\u00a0\u00bb header_2_text_align_phone=\u00a0\u00bbleft\u00a0\u00bb header_2_text_align_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_2_font_size_tablet=\u00a0\u00bb32px\u00a0\u00bb header_2_font_size_phone=\u00a0\u00bb21px\u00a0\u00bb header_2_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_2_line_height_tablet=\u00a0\u00bb1.5em\u00a0\u00bb header_2_line_height_phone=\u00a0\u00bb0.8em\u00a0\u00bb header_2_line_height_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_3_text_align_tablet=\u00a0\u00bb\u00a0\u00bb header_3_text_align_phone=\u00a0\u00bbleft\u00a0\u00bb header_3_text_align_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_3_font_size_tablet=\u00a0\u00bb19px\u00a0\u00bb header_3_font_size_phone=\u00a0\u00bb17px\u00a0\u00bb header_3_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3>Meilleurs endroits \u00e0 visiter \u00e0 Saint Martin<\/h3>\n<h2>Marigot<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb2_3,1_3&Prime; custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; custom_margin=\u00a0\u00bb-50px||||false|false\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb\u00a0\u00bb custom_padding_phone=\u00a0\u00bb15px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb2_3&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; text_font=\u00a0\u00bbPoppins|300|||||||\u00a0\u00bb text_font_size=\u00a0\u00bb16px\u00a0\u00bb text_line_height=\u00a0\u00bb2em\u00a0\u00bb text_orientation=\u00a0\u00bbjustified\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb\u00a0\u00bb text_font_size_phone=\u00a0\u00bb16px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<a href=\"https:\/\/goo.gl\/maps\/TVkYwH6gWm3AbwBF7\" target=\"_blank\" rel=\"noopener\">Marigot<\/a> est la ville principale et capitale de la collectivit\u00e9 fran\u00e7aise de Saint-Martin, situ\u00e9e sur la c\u00f4te ouest de l&rsquo;\u00eele.<\/p>\n<p>De plus, Marigot ressemble \u00e0 une ville carib\u00e9enne typique, avec ses maisons en pain d&rsquo;\u00e9pices et ses bistrots en terrasse. De plus, la ville abrite un grand march\u00e9 artisanal ouvert au public tous les mercredis et samedis matins. Enfin, le port pittoresque et le Fort Saint-Louis, qu&rsquo;il vaut la peine de gravir pour admirer la vue sur la ville, offrent une exp\u00e9rience passionnante aux visiteurs.[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/soeasytravelinsurance.com\/wp-content\/uploads\/2022\/06\/saintmartin1.jpg\u00a0\u00bb alt=\u00a0\u00bbSaint Martin Travel Insurance\u00a0\u00bb title_text=\u00a0\u00bbSaint Martin Travel Insurance\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb90%\u00a0\u00bb width_tablet=\u00a0\u00bb\u00a0\u00bb width_phone=\u00a0\u00bb\u00a0\u00bb width_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb admin_label=\u00a0\u00bbAbout\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.4&Prime; custom_margin_tablet=\u00a0\u00bb\u00a0\u00bb custom_margin_phone=\u00a0\u00bb1px||||false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_padding=\u00a0\u00bb16px||0px|||\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb\u00a0\u00bb custom_padding_phone=\u00a0\u00bb9px||5px||false|false\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.16&Prime; custom_margin_tablet=\u00a0\u00bb\u00a0\u00bb custom_margin_phone=\u00a0\u00bb20px||||false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.16&Prime; text_font=\u00a0\u00bb||||||||\u00a0\u00bb text_font_size=\u00a0\u00bb15px\u00a0\u00bb text_line_height=\u00a0\u00bb2em\u00a0\u00bb header_font=\u00a0\u00bb||||||||\u00a0\u00bb header_2_font=\u00a0\u00bbMontserrat|800|||||||\u00a0\u00bb header_2_font_size=\u00a0\u00bb27px\u00a0\u00bb header_2_line_height=\u00a0\u00bb1.5em\u00a0\u00bb header_3_font=\u00a0\u00bbRubik|500||on|||||\u00a0\u00bb header_3_text_color=\u00a0\u00bb#f58233&Prime; header_3_font_size=\u00a0\u00bb19px\u00a0\u00bb header_3_letter_spacing=\u00a0\u00bb2px\u00a0\u00bb max_width=\u00a0\u00bb500px\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb\u00a0\u00bb text_font_size_phone=\u00a0\u00bb14px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_text_align_tablet=\u00a0\u00bb\u00a0\u00bb header_text_align_phone=\u00a0\u00bbcenter\u00a0\u00bb header_text_align_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_2_text_align_tablet=\u00a0\u00bb\u00a0\u00bb header_2_text_align_phone=\u00a0\u00bbleft\u00a0\u00bb header_2_text_align_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_2_font_size_tablet=\u00a0\u00bb32px\u00a0\u00bb header_2_font_size_phone=\u00a0\u00bb21px\u00a0\u00bb header_2_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_2_line_height_tablet=\u00a0\u00bb1.5em\u00a0\u00bb header_2_line_height_phone=\u00a0\u00bb0.8em\u00a0\u00bb header_2_line_height_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_3_text_align_tablet=\u00a0\u00bb\u00a0\u00bb header_3_text_align_phone=\u00a0\u00bbleft\u00a0\u00bb header_3_text_align_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_3_font_size_tablet=\u00a0\u00bb19px\u00a0\u00bb header_3_font_size_phone=\u00a0\u00bb17px\u00a0\u00bb header_3_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>Loterie Farm<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb2_3,1_3&Prime; custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; custom_margin=\u00a0\u00bb-50px||||false|false\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb\u00a0\u00bb custom_padding_phone=\u00a0\u00bb15px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb2_3&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; text_font=\u00a0\u00bbPoppins|300|||||||\u00a0\u00bb text_font_size=\u00a0\u00bb16px\u00a0\u00bb text_line_height=\u00a0\u00bb2em\u00a0\u00bb text_orientation=\u00a0\u00bbjustified\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb\u00a0\u00bb text_font_size_phone=\u00a0\u00bb16px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]La <a href=\"https:\/\/g.page\/LoterieFarm?share\" target=\"_blank\" rel=\"noopener\">Loterie Farm<\/a> est un sanctuaire naturel paisible situ\u00e9 sur le Pic Paradis, c\u00f4t\u00e9 fran\u00e7ais de l&rsquo;\u00eele de Saint-Martin.<\/p>\n<p>Le lieu s&rsquo;\u00e9tend sur une superficie d&rsquo;environ 0,4 km\u00b2 de v\u00e9g\u00e9tation luxuriante, \u00e0 explorer gr\u00e2ce aux nombreux sentiers de randonn\u00e9e ou m\u00eame en tyrolienne au-dessus de la canop\u00e9e de manguiers et d&rsquo;acajous. Ceux qui pr\u00e9f\u00e8rent une journ\u00e9e de repos et de d\u00e9tente appr\u00e9cieront le club de plage chic, o\u00f9 chaises longues, lits de repos et cabanas luxueux entourent les bassins \u00e9tincelants, entour\u00e9s de ruisseaux et de bosquets de fleurs tropicales.[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/soeasytravelinsurance.com\/wp-content\/uploads\/2022\/06\/saintmartin2.jpg\u00a0\u00bb alt=\u00a0\u00bbSaint Martin Travel Insurance\u00a0\u00bb title_text=\u00a0\u00bbSaint Martin Travel Insurance\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb90%\u00a0\u00bb width_tablet=\u00a0\u00bb\u00a0\u00bb width_phone=\u00a0\u00bb\u00a0\u00bb width_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb admin_label=\u00a0\u00bbAbout\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; custom_margin_tablet=\u00a0\u00bb\u00a0\u00bb custom_margin_phone=\u00a0\u00bb1px||||false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_padding=\u00a0\u00bb16px||0px|||\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb\u00a0\u00bb custom_padding_phone=\u00a0\u00bb9px||5px||false|false\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.16&Prime; custom_margin_tablet=\u00a0\u00bb\u00a0\u00bb custom_margin_phone=\u00a0\u00bb20px||||false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; text_font=\u00a0\u00bb||||||||\u00a0\u00bb text_font_size=\u00a0\u00bb15px\u00a0\u00bb text_line_height=\u00a0\u00bb2em\u00a0\u00bb header_font=\u00a0\u00bb||||||||\u00a0\u00bb header_2_font=\u00a0\u00bbMontserrat|800|||||||\u00a0\u00bb header_2_font_size=\u00a0\u00bb27px\u00a0\u00bb header_2_line_height=\u00a0\u00bb1.5em\u00a0\u00bb header_3_font=\u00a0\u00bbRubik|500||on|||||\u00a0\u00bb header_3_text_color=\u00a0\u00bb#f58233&Prime; header_3_font_size=\u00a0\u00bb19px\u00a0\u00bb header_3_letter_spacing=\u00a0\u00bb2px\u00a0\u00bb max_width=\u00a0\u00bb500px\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb\u00a0\u00bb text_font_size_phone=\u00a0\u00bb14px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_text_align_tablet=\u00a0\u00bb\u00a0\u00bb header_text_align_phone=\u00a0\u00bbcenter\u00a0\u00bb header_text_align_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_2_text_align_tablet=\u00a0\u00bb\u00a0\u00bb header_2_text_align_phone=\u00a0\u00bbleft\u00a0\u00bb header_2_text_align_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_2_font_size_tablet=\u00a0\u00bb32px\u00a0\u00bb header_2_font_size_phone=\u00a0\u00bb21px\u00a0\u00bb header_2_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_2_line_height_tablet=\u00a0\u00bb1.5em\u00a0\u00bb header_2_line_height_phone=\u00a0\u00bb0.8em\u00a0\u00bb header_2_line_height_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_3_text_align_tablet=\u00a0\u00bb\u00a0\u00bb header_3_text_align_phone=\u00a0\u00bbleft\u00a0\u00bb header_3_text_align_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_3_font_size_tablet=\u00a0\u00bb19px\u00a0\u00bb header_3_font_size_phone=\u00a0\u00bb17px\u00a0\u00bb header_3_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>Plage de Friars\u2019 Bay<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb2_3,1_3&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb4px|||||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb2_3&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; text_font=\u00a0\u00bbPoppins|300|||||||\u00a0\u00bb text_font_size=\u00a0\u00bb16px\u00a0\u00bb text_line_height=\u00a0\u00bb2em\u00a0\u00bb text_orientation=\u00a0\u00bbjustified\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb\u00a0\u00bb text_font_size_phone=\u00a0\u00bb16px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]Situ\u00e9e au nord-ouest de Saint-Martin, la <a href=\"https:\/\/maps.app.goo.gl\/DRRTLSmPPLnSrH5GA\" target=\"_blank\" rel=\"noopener\">plage de Friars\u2019 Bay<\/a> (Anse des P\u00e8res) est une plage familiale r\u00e9put\u00e9e.<\/p>\n<p>Elle est particuli\u00e8rement appr\u00e9ci\u00e9e des visiteurs europ\u00e9ens et am\u00e9ricains pour ses caf\u00e9s et bars. Au coucher du soleil, la plage se transforme en un lieu de f\u00eate anim\u00e9, avec des airs de rock et de reggae. L&rsquo;un des \u00e9v\u00e9nements les plus importants est la Full Moon Party, qui attire les touristes avides de d\u00e9couvrir la vie nocturne de l&rsquo;\u00eele. Bien qu&rsquo;elle ne soit pas aussi imposante que la l\u00e9gendaire Full Moon Party de Koh Samui, en Tha\u00eflande, c&rsquo;est l&rsquo;une des f\u00eates de plage les plus importantes et les plus c\u00e9l\u00e8bres de la r\u00e9gion.[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/soeasytravelinsurance.com\/wp-content\/uploads\/2025\/08\/friars-bay-beach.jpg\u00a0\u00bb alt=\u00a0\u00bbSaint Martin Travel Insurance\u00a0\u00bb title_text=\u00a0\u00bbSaint Martin Travel Insurance\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb90%\u00a0\u00bb width_tablet=\u00a0\u00bb\u00a0\u00bb width_phone=\u00a0\u00bb\u00a0\u00bb width_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; custom_padding_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb||50px|||\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb||50px|||\u00a0\u00bb custom_padding_phone=\u00a0\u00bb||20px||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row disabled_on=\u00a0\u00bbon|on|on\u00a0\u00bb _builder_version=\u00a0\u00bb4.21.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb max_width=\u00a0\u00bb2002px\u00a0\u00bb custom_padding=\u00a0\u00bb||19px|||\u00a0\u00bb disabled=\u00a0\u00bbon\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_divider color=\u00a0\u00bb#d7dce1&Prime; divider_weight=\u00a0\u00bb1px\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb max_width=\u00a0\u00bb100%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row disabled_on=\u00a0\u00bbon|on|on\u00a0\u00bb _builder_version=\u00a0\u00bb4.21.0&Prime; custom_margin_tablet=\u00a0\u00bb\u00a0\u00bb custom_margin_phone=\u00a0\u00bb20px||||false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb custom_padding=\u00a0\u00bb||0px|||\u00a0\u00bb disabled=\u00a0\u00bbon\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.16&Prime; text_font=\u00a0\u00bb||||||||\u00a0\u00bb text_font_size=\u00a0\u00bb15px\u00a0\u00bb text_line_height=\u00a0\u00bb2em\u00a0\u00bb header_font=\u00a0\u00bb||||||||\u00a0\u00bb header_2_font=\u00a0\u00bbMontserrat|800|||||||\u00a0\u00bb header_2_text_align=\u00a0\u00bbcenter\u00a0\u00bb header_2_font_size=\u00a0\u00bb32px\u00a0\u00bb header_2_line_height=\u00a0\u00bb1.5em\u00a0\u00bb header_3_font=\u00a0\u00bbRubik|500||on|||||\u00a0\u00bb header_3_text_align=\u00a0\u00bbcenter\u00a0\u00bb header_3_text_color=\u00a0\u00bb#f58233&Prime; header_3_font_size=\u00a0\u00bb19px\u00a0\u00bb header_3_letter_spacing=\u00a0\u00bb2px\u00a0\u00bb max_width=\u00a0\u00bb500px\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb\u00a0\u00bb text_font_size_phone=\u00a0\u00bb14px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_text_align_tablet=\u00a0\u00bb\u00a0\u00bb header_text_align_phone=\u00a0\u00bbcenter\u00a0\u00bb header_text_align_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_2_text_align_tablet=\u00a0\u00bb\u00a0\u00bb header_2_text_align_phone=\u00a0\u00bbcenter\u00a0\u00bb header_2_text_align_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_2_font_size_tablet=\u00a0\u00bb32px\u00a0\u00bb header_2_font_size_phone=\u00a0\u00bb21px\u00a0\u00bb header_2_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_2_line_height_tablet=\u00a0\u00bb1.5em\u00a0\u00bb header_2_line_height_phone=\u00a0\u00bb0.8em\u00a0\u00bb header_2_line_height_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_3_text_align_tablet=\u00a0\u00bb\u00a0\u00bb header_3_text_align_phone=\u00a0\u00bbcenter\u00a0\u00bb header_3_text_align_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_3_font_size_tablet=\u00a0\u00bb19px\u00a0\u00bb header_3_font_size_phone=\u00a0\u00bb17px\u00a0\u00bb header_3_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3>Our travel blog<\/h3>\n<p>[\/et_pb_text][et_pb_blog fullwidth=\u00a0\u00bboff\u00a0\u00bb posts_number=\u00a0\u00bb3&Prime; include_categories=\u00a0\u00bb13&Prime; _builder_version=\u00a0\u00bb4.19.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_blog][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb max_width=\u00a0\u00bb2002px\u00a0\u00bb custom_padding=\u00a0\u00bb||19px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_divider color=\u00a0\u00bb#d7dce1&Prime; divider_weight=\u00a0\u00bb1px\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb max_width=\u00a0\u00bb100%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; make_equal=\u00a0\u00bbon\u00a0\u00bb use_custom_gutter=\u00a0\u00bbon\u00a0\u00bb gutter_width=\u00a0\u00bb2&Prime; specialty=\u00a0\u00bbon\u00a0\u00bb padding_right_1=\u00a0\u00bb12%\u00a0\u00bb padding_bottom_1=\u00a0\u00bb40px\u00a0\u00bb padding_top_bottom_link_1=\u00a0\u00bbfalse\u00a0\u00bb padding_left_right_link_1=\u00a0\u00bbfalse\u00a0\u00bb padding_1_tablet=\u00a0\u00bb|0px|0px||false|false\u00a0\u00bb padding_1_phone=\u00a0\u00bb|0px|||false|false\u00a0\u00bb padding_1_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb use_background_color_gradient=\u00a0\u00bbon\u00a0\u00bb background_color_gradient_type=\u00a0\u00bbcircular\u00a0\u00bb background_color_gradient_direction_radial=\u00a0\u00bbtop right\u00a0\u00bb background_color_gradient_stops=\u00a0\u00bbrgba(0,0,0,0.77) 10%|rgba(0,0,0,0.71) 100%\u00a0\u00bb background_color_gradient_overlays_image=\u00a0\u00bbon\u00a0\u00bb background_color_gradient_start=\u00a0\u00bbrgba(0,0,0,0.77)\u00a0\u00bb background_color_gradient_start_position=\u00a0\u00bb10%\u00a0\u00bb background_color_gradient_end=\u00a0\u00bbrgba(0,0,0,0.71)\u00a0\u00bb background_image=\u00a0\u00bbhttps:\/\/soeasytravelinsurance.com\/wp-content\/uploads\/2022\/04\/view-air-plane-wing-during-take-off-landing-1-scaled-1.jpg\u00a0\u00bb background_position=\u00a0\u00bbtop_center\u00a0\u00bb background_vertical_offset=\u00a0\u00bb42%\u00a0\u00bb custom_padding=\u00a0\u00bb36px||0px|||\u00a0\u00bb background_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb background_vertical_offset_phone=\u00a0\u00bb70%\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/soeasytravelinsurance.com\/wp-content\/uploads\/2022\/06\/logo-1-36.png\u00a0\u00bb alt=\u00a0\u00bbSoeasy Travel Insurance\u00a0\u00bb title_text=\u00a0\u00bbSoeasy Travel Insurance\u00a0\u00bb url=\u00a0\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoiaG9tZV91cmwiLCJzZXR0aW5ncyI6e319@\u00a0\u00bb _builder_version=\u00a0\u00bb4.17.4&Prime; _dynamic_attributes=\u00a0\u00bburl\u00a0\u00bb _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb||||false|false\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb||60px||false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bboff|desktop\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.21.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bbPoppins|300|||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb text_line_height=\u00a0\u00bb1.6em\u00a0\u00bb header_3_font=\u00a0\u00bbMontserrat|700|||||||\u00a0\u00bb header_3_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb header_3_font_size=\u00a0\u00bb21px\u00a0\u00bb custom_margin=\u00a0\u00bb60px||30px||false|false\u00a0\u00bb text_font_size_tablet=\u00a0\u00bb17px\u00a0\u00bb text_font_size_phone=\u00a0\u00bb16px\u00a0\u00bb text_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3>Assurance voyage<\/h3>\n<p>Assurance voyage, assurance voyage pour le visa Schengen, polices d&rsquo;assurance voyage unique et multi-voyages pour l&rsquo;Europe et le monde entier.[\/et_pb_text][et_pb_button button_url=\u00a0\u00bbhttps:\/\/my.soeasytravelinsurance.com\/login\u00a0\u00bb url_new_window=\u00a0\u00bbon\u00a0\u00bb button_text=\u00a0\u00bbLOGIN AGENT\u00a0\u00bb button_alignment=\u00a0\u00bbleft\u00a0\u00bb button_alignment_tablet=\u00a0\u00bbcenter\u00a0\u00bb button_alignment_last_edited=\u00a0\u00bboff|tablet\u00a0\u00bb _builder_version=\u00a0\u00bb4.21.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_size=\u00a0\u00bb17px\u00a0\u00bb button_text_color=\u00a0\u00bb#ffffff\u00a0\u00bb button_bg_color=\u00a0\u00bb#f58233&Prime; button_border_width=\u00a0\u00bb0px\u00a0\u00bb button_border_radius=\u00a0\u00bb5px\u00a0\u00bb button_letter_spacing=\u00a0\u00bb2px\u00a0\u00bb button_font=\u00a0\u00bbRoboto|700||on|||||\u00a0\u00bb button_icon=\u00a0\u00bb&#x45;||divi||400&Prime; button_on_hover=\u00a0\u00bboff\u00a0\u00bb custom_padding=\u00a0\u00bb7px|37px|7px|20px|true|false\u00a0\u00bb button_text_size_tablet=\u00a0\u00bb21px\u00a0\u00bb button_text_size_phone=\u00a0\u00bb15px\u00a0\u00bb button_text_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb button_bg_color_tablet=\u00a0\u00bb#f58233&Prime; button_bg_color_phone=\u00a0\u00bb#f58233&Prime; button_bg_color_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb button_border_radius_tablet=\u00a0\u00bb0px\u00a0\u00bb button_border_radius_phone=\u00a0\u00bb5px\u00a0\u00bb button_border_radius_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb button_border_radius__hover=\u00a0\u00bb5px\u00a0\u00bb button_border_radius__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb button_letter_spacing__hover=\u00a0\u00bb3px\u00a0\u00bb button_letter_spacing__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb][\/et_pb_button][et_pb_image src=\u00a0\u00bbhttps:\/\/soeasytravelinsurance.com\/wp-content\/uploads\/2025\/10\/google.jpg\u00a0\u00bb title_text=\u00a0\u00bbgoogle\u00a0\u00bb url=\u00a0\u00bbhttps:\/\/www.google.com\/search?sca_esv=99f1a6d769628b16&#038;rlz=1C1GCEA_enCY999CY999&#038;sxsrf=AE3TifPnPloy8Gy98t7WTUEFs6CU1_2uCg:1758795298326&#038;si=AMgyJEtREmoPL4P1I5IDCfuA8gybfVI2d5Uj7QMwYCZHKDZ-E10Q063rmjDeX2XWDlW7RMUktuOkEGxDgz6ZPpq_ffNAbD199S2iwoqZZvO6HMfw5lCjfGqqpqDIdtgmx9erEMengjgOLQqyyUbxjsZllOfy7b3zKw%3D%3D&#038;q=SoEasy+Travel+Insurance+Reviews&#038;sa=X&#038;ved=2ahUKEwin7PSH1_OPAxWdTqQEHXI0KkEQ0bkNegQIIhAD\u00a0\u00bb url_new_window=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb||||false|false\u00a0\u00bb border_radii=\u00a0\u00bbon|10px|10px|10px|10px\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_code _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_orientation=\u00a0\u00bbleft\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb max_width=\u00a0\u00bb100%\u00a0\u00bb custom_margin=\u00a0\u00bb||||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb||||false|false\u00a0\u00bb link_option_url=\u00a0\u00bbhttps:\/\/www.trustpilot.com\/review\/soeasytravelinsurance.com\u00a0\u00bb link_option_url_new_window=\u00a0\u00bbon\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<div class=\"gutensuite-reviewkit_fpln_mcts gutensuite-reviewkit_fpln_common\"><div class=\"gutensuite-reviewkit_fpln_inner_left\"><span class=\"review_us_one\">Excellent<\/span><div class=\"gutensuite-reviewkit_score\"><span class=\"gutensuite-reviewkit_orignal_rcount\">4.8<\/span><span class=\"gutensuite-reviewkit_out_of\"> out of 5<\/span><\/div><\/div><div class=\"gutensuite-reviewkit_fpln_inner_right\"><img decoding=\"async\" src=\"https:\/\/soeasytravelinsurance.com\/wp-content\/plugins\/gutensuite-reviewkit\/assets\/images\/single-star.svg\" alt=\"Trustpilot logo\"  style=\"width: 20px;\" \/><span class=\"place_name\"> Trustpilot<\/span><\/div><\/div>[\/et_pb_code][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _dynamic_attributes=\u00a0\u00bbcontent\u00a0\u00bb _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bbPoppins||||||||\u00a0\u00bb text_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb text_font_size=\u00a0\u00bb16px\u00a0\u00bb link_font=\u00a0\u00bbPoppins||||||||\u00a0\u00bb link_text_color=\u00a0\u00bb#f58233&Prime; link_font_size=\u00a0\u00bb16px\u00a0\u00bb width=\u00a0\u00bb200%\u00a0\u00bb width_tablet=\u00a0\u00bb200%\u00a0\u00bb width_phone=\u00a0\u00bb98%\u00a0\u00bb width_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb max_width=\u00a0\u00bb200%\u00a0\u00bb max_width_tablet=\u00a0\u00bb200%\u00a0\u00bb max_width_phone=\u00a0\u00bb99%\u00a0\u00bb max_width_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb custom_margin=\u00a0\u00bb100px||||false|false\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb100px||||false|false\u00a0\u00bb custom_margin_phone=\u00a0\u00bb100px||||false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;]@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoiY3VycmVudF9kYXRlIiwic2V0dGluZ3MiOnsiYmVmb3JlIjoiQ29weXJpZ2h0IMKpICIsImFmdGVyIjoiIFNvIEVhc3kgVHJhdmVsIEluc3VyYW5jZS4gPGEgaHJlZj1cImh0dHBzOi8vc29lYXN5dHJhdmVsaW5zdXJhbmNlLmNvbS9wcml2YWN5LXBvbGljeS9cIiB0YXJnZXQ9XCJfYmxhbmtcIiByZWw9XCJub29wZW5lclwiPlBvbGl0aXF1ZSBkZSBjb25maWRlbnRpYWxpdMOpPC9hPiAgSSA8YSBocmVmPVwiaHR0cHM6Ly9zb2Vhc3l0cmF2ZWxpbnN1cmFuY2UuY29tL3Rlcm1zLWFuZC1jb25kaXRpb25zL1wiIHRhcmdldD1cIl9ibGFua1wiIHJlbD1cIm5vb3BlbmVyXCI+Q29uZGl0aW9ucyBnw6luw6lyYWxlcyA8L2E+ICAgIiwiZGF0ZV9mb3JtYXQiOiJjdXN0b20iLCJjdXN0b21fZGF0ZV9mb3JtYXQiOiJZIn19@[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; specialty_columns=\u00a0\u00bb2&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][\/et_pb_column][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Assurance voyage Saint Martin Saint Martin est une \u00eele carib\u00e9enne dynamique o\u00f9 l&rsquo;\u00e9l\u00e9gance fran\u00e7aise et le charme n\u00e9erlandais se marient \u00e0 merveille avec des eaux turquoise, des plages dor\u00e9es et une sc\u00e8ne culturelle dynamique. Que vous savouriez la cuisine gastronomique de Marigot, profitiez de la vie nocturne de Philipsburg, vous d\u00e9tendiez \u00e0 la Baie Orientale [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":249531,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-template-blank.php","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","cybocfi_hide_featured_image":"","footnotes":""},"class_list":["post-256707","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Assurance voyage Saint Martin - SoEasy Travel Insurance<\/title>\n<meta name=\"description\" content=\"L&#039; assurance voyage Saint Martin couvre les personnes voyageant dans les pays Schengen, en Europe et dans le monde entier pour une assurance multi-voyages unique\/annuelle.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/soeasytravelinsurance.com\/saint-martin-travel-insurance\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Assurance voyage Saint Martin\" \/>\n<meta property=\"og:description\" content=\"L&#039; assurance voyage Saint Martin couvre les personnes voyageant dans les pays Schengen, en Europe et dans le monde entier pour une assurance multi-voyages unique\/annuelle.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/soeasytravelinsurance.com\/saint-martin-travel-insurance\/\" \/>\n<meta property=\"og:site_name\" content=\"SoEasy Travel Insurance\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-18T12:16:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/soeasytravelinsurance.com\/wp-content\/uploads\/2022\/06\/saintmartin1.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:description\" content=\"L&#039; assurance voyage Saint Martin couvre les personnes voyageant dans les pays Schengen, en Europe et dans le monde entier pour une assurance multi-voyages unique\/annuelle.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/soeasytravelinsurance.com\/wp-content\/uploads\/2022\/06\/saintmartin1.jpg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/soeasytravelinsurance.com\\\/saint-martin-travel-insurance\\\/\",\"url\":\"https:\\\/\\\/soeasytravelinsurance.com\\\/saint-martin-travel-insurance\\\/\",\"name\":\"Assurance voyage Saint Martin - SoEasy Travel Insurance\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/soeasytravelinsurance.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/soeasytravelinsurance.com\\\/saint-martin-travel-insurance\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/soeasytravelinsurance.com\\\/saint-martin-travel-insurance\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/soeasytravelinsurance.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/saintmartin1.jpg\",\"datePublished\":\"2022-04-19T07:59:28+00:00\",\"dateModified\":\"2025-12-18T12:16:24+00:00\",\"description\":\"L' assurance voyage Saint Martin couvre les personnes voyageant dans les pays Schengen, en Europe et dans le monde entier pour une assurance multi-voyages unique\\\/annuelle.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/soeasytravelinsurance.com\\\/saint-martin-travel-insurance\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/soeasytravelinsurance.com\\\/saint-martin-travel-insurance\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/soeasytravelinsurance.com\\\/saint-martin-travel-insurance\\\/#primaryimage\",\"url\":\"https:\\\/\\\/soeasytravelinsurance.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/saintmartin1.jpg\",\"contentUrl\":\"https:\\\/\\\/soeasytravelinsurance.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/saintmartin1.jpg\",\"width\":900,\"height\":540},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/soeasytravelinsurance.com\\\/saint-martin-travel-insurance\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Travel Insurance\",\"item\":\"https:\\\/\\\/soeasytravelinsurance.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Assurance voyage Saint Martin\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/soeasytravelinsurance.com\\\/#website\",\"url\":\"https:\\\/\\\/soeasytravelinsurance.com\\\/\",\"name\":\"SoEasy Travel Insurance\",\"description\":\"Whether it\u2019s a beach holiday with the family, a business trip, or a training trip away at SoEasy international travel Insurance, you can buy the best single trip travel medical insurance and multi-trip travel medical insurance online.\",\"publisher\":{\"@id\":\"https:\\\/\\\/soeasytravelinsurance.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/soeasytravelinsurance.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/soeasytravelinsurance.com\\\/#organization\",\"name\":\"So Easy Travel Insurance\",\"url\":\"https:\\\/\\\/soeasytravelinsurance.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/soeasytravelinsurance.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/soeasytravelinsurance.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo-5.png\",\"contentUrl\":\"https:\\\/\\\/soeasytravelinsurance.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo-5.png\",\"width\":210,\"height\":66,\"caption\":\"So Easy Travel Insurance\"},\"image\":{\"@id\":\"https:\\\/\\\/soeasytravelinsurance.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Assurance voyage Saint Martin - SoEasy Travel Insurance","description":"L' assurance voyage Saint Martin couvre les personnes voyageant dans les pays Schengen, en Europe et dans le monde entier pour une assurance multi-voyages unique\/annuelle.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/soeasytravelinsurance.com\/saint-martin-travel-insurance\/","og_locale":"fr_FR","og_type":"article","og_title":"Assurance voyage Saint Martin","og_description":"L' assurance voyage Saint Martin couvre les personnes voyageant dans les pays Schengen, en Europe et dans le monde entier pour une assurance multi-voyages unique\/annuelle.","og_url":"https:\/\/soeasytravelinsurance.com\/saint-martin-travel-insurance\/","og_site_name":"SoEasy Travel Insurance","article_modified_time":"2025-12-18T12:16:24+00:00","og_image":[{"url":"https:\/\/soeasytravelinsurance.com\/wp-content\/uploads\/2022\/06\/saintmartin1.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_description":"L' assurance voyage Saint Martin couvre les personnes voyageant dans les pays Schengen, en Europe et dans le monde entier pour une assurance multi-voyages unique\/annuelle.","twitter_image":"https:\/\/soeasytravelinsurance.com\/wp-content\/uploads\/2022\/06\/saintmartin1.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/soeasytravelinsurance.com\/saint-martin-travel-insurance\/","url":"https:\/\/soeasytravelinsurance.com\/saint-martin-travel-insurance\/","name":"Assurance voyage Saint Martin - SoEasy Travel Insurance","isPartOf":{"@id":"https:\/\/soeasytravelinsurance.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/soeasytravelinsurance.com\/saint-martin-travel-insurance\/#primaryimage"},"image":{"@id":"https:\/\/soeasytravelinsurance.com\/saint-martin-travel-insurance\/#primaryimage"},"thumbnailUrl":"https:\/\/soeasytravelinsurance.com\/wp-content\/uploads\/2022\/06\/saintmartin1.jpg","datePublished":"2022-04-19T07:59:28+00:00","dateModified":"2025-12-18T12:16:24+00:00","description":"L' assurance voyage Saint Martin couvre les personnes voyageant dans les pays Schengen, en Europe et dans le monde entier pour une assurance multi-voyages unique\/annuelle.","breadcrumb":{"@id":"https:\/\/soeasytravelinsurance.com\/saint-martin-travel-insurance\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/soeasytravelinsurance.com\/saint-martin-travel-insurance\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/soeasytravelinsurance.com\/saint-martin-travel-insurance\/#primaryimage","url":"https:\/\/soeasytravelinsurance.com\/wp-content\/uploads\/2022\/06\/saintmartin1.jpg","contentUrl":"https:\/\/soeasytravelinsurance.com\/wp-content\/uploads\/2022\/06\/saintmartin1.jpg","width":900,"height":540},{"@type":"BreadcrumbList","@id":"https:\/\/soeasytravelinsurance.com\/saint-martin-travel-insurance\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Travel Insurance","item":"https:\/\/soeasytravelinsurance.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Assurance voyage Saint Martin"}]},{"@type":"WebSite","@id":"https:\/\/soeasytravelinsurance.com\/#website","url":"https:\/\/soeasytravelinsurance.com\/","name":"SoEasy Travel Insurance","description":"Whether it\u2019s a beach holiday with the family, a business trip, or a training trip away at SoEasy international travel Insurance, you can buy the best single trip travel medical insurance and multi-trip travel medical insurance online.","publisher":{"@id":"https:\/\/soeasytravelinsurance.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/soeasytravelinsurance.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/soeasytravelinsurance.com\/#organization","name":"So Easy Travel Insurance","url":"https:\/\/soeasytravelinsurance.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/soeasytravelinsurance.com\/#\/schema\/logo\/image\/","url":"https:\/\/soeasytravelinsurance.com\/wp-content\/uploads\/2022\/04\/logo-5.png","contentUrl":"https:\/\/soeasytravelinsurance.com\/wp-content\/uploads\/2022\/04\/logo-5.png","width":210,"height":66,"caption":"So Easy Travel Insurance"},"image":{"@id":"https:\/\/soeasytravelinsurance.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/soeasytravelinsurance.com\/fr\/wp-json\/wp\/v2\/pages\/256707","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/soeasytravelinsurance.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/soeasytravelinsurance.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/soeasytravelinsurance.com\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/soeasytravelinsurance.com\/fr\/wp-json\/wp\/v2\/comments?post=256707"}],"version-history":[{"count":1,"href":"https:\/\/soeasytravelinsurance.com\/fr\/wp-json\/wp\/v2\/pages\/256707\/revisions"}],"predecessor-version":[{"id":288677,"href":"https:\/\/soeasytravelinsurance.com\/fr\/wp-json\/wp\/v2\/pages\/256707\/revisions\/288677"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/soeasytravelinsurance.com\/fr\/wp-json\/wp\/v2\/media\/249531"}],"wp:attachment":[{"href":"https:\/\/soeasytravelinsurance.com\/fr\/wp-json\/wp\/v2\/media?parent=256707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}